{"id":5194,"date":"2015-04-22T00:00:00","date_gmt":"2015-04-22T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2015\/04\/22\/ceden-toros-primero-de-la-serie\/"},"modified":"2015-04-22T00:00:00","modified_gmt":"2015-04-22T07:00:00","slug":"ceden-toros-primero-de-la-serie","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/ceden-toros-primero-de-la-serie\/2015\/04\/","title":{"rendered":"Ceden Toros primero de la serie"},"content":{"rendered":"<p><strong>TIJUANA, Baja California (TorosdeTijuana.com- Armando Esquivel) 21 de abril del 2015 &#8211; <\/strong>Miguel Olivo bate\u00f3 cuadrangular de dos carreras, pero los Toros de Tijuana reaccionaron tarde y cayeron 2-8 ante Guerreros de Oaxaca, al abrir la serie en el estadio Gasmart.<\/p>\n<p>El equipo fronterizo sufri\u00f3 apenas su segundo rev\u00e9s en casa en esta temporada 2015 de la Liga Mexicana de Beisbol (LMB) y a pesar del descalabro se mantuvo en la primera posici\u00f3n de la Zona Norte, al mostrar n\u00fameros de 10-5 en ganados y perdidos, pero ahora comparte la posici\u00f3n de honor con la escuadra de Rieleros de Aguascalientes.<\/p>\n<p>Por su parte, los Guerreros de Oaxaca ligaron su cuarta victoria gracias a Mario Valenzuela, quien produjo cinco carreras en una noche en la que descarg\u00f3 cuadrangular con uno a bordo y doblete con las bases llenas, sin embargo, los comandados por Enrique \u201cChe\u201d Reyes siguen en el \u00faltimo lugar de la Zona Sur, ahora con marca de 5-10.<\/p>\n<p>En las acciones sobre el diamante, los \u201cb\u00e9licos\u201d se adelantaron en la parte alta de la segunda entrada cuando Yuniesky S\u00e1nchez conect\u00f3 imparable, se rob\u00f3 la intermedia, para luego avanzar a la antesala con sencillo de \u00c9rick Rodr\u00edguez y anotar con un \u201cwild pitch\u201d del abridor de Toros, Terance Marin.<\/p>\n<p>Para la cuarta ronda doblaron su margen favorable y fue por la misma v\u00eda, ya que el propio Yuniesky S\u00e1nchez abri\u00f3 con triple y luego de pasaportes  consecutivos a Mario Valenzuela y Tim Torres, logr\u00f3 timbrar con otro lanzamiento descontrolado de Terance Marin que no pudo controlar Miguel Olivo.<\/p>\n<p>Para el sexto rollo la visita tom\u00f3 rumbo a la victoria con el bombazo de dos carreras de Mario Valenzuela por encima de la estepa izquierda y para la s\u00e9ptima el mismo jardinero sudcaliforniano se present\u00f3 a batear con el \u201crancho ardiendo\u201d y respondi\u00f3 con doblete para vaciar las almohadillas y poner la pizarra 7-0.<\/p>\n<p>La tropa del manejador dominicano Eddie D\u00edaz intent\u00f3 reaccionar en la parte baja de ese mismo cap\u00edtulo con estacazo de dos carreras de Miguel Olivo, quien se llev\u00f3 por delante a Luis Mauricio Su\u00e1rez, pero los de la \u201cVerde Antequera\u201d agregaron una m\u00e1s en la octava con elevado de sacrificio de Yancarlo Angulo para maquillar el marcador final de 8-2.<\/p>\n<p>En la lomita el ganador fue el zurdo Alejandro Soto con una soberbia actuaci\u00f3n de seis entradas con apenas dos imparables, una carrera, dos pasaportes y un chocolate. En su auxilio circularon Mart\u00edn Sotelo para la otra carrera, Rodolfo Aguilar, Hugo Guti\u00e9rrez y H\u00e9ctor S\u00e1nchez.<\/p>\n<p>El descalabro fue al r\u00e9cord de Terance Marin quien se llev\u00f3 dos carreras y seis hits en cinco cap\u00edtulos. El estadounidense fue elevado por Francisco Liz\u00e1rraga, Manny Barreda, Rafael D\u00edaz y Dennys Reyes.<\/p>\n<p>PEGATE A LOS TOROS<\/p>\n<p>Los Toros de Tijuana enfrentar\u00e1n ma\u00f1ana (mi\u00e9rcoles) a los Guerreros de Oaxaca en el segundo choque de la serie, en un duelo que est\u00e1 programado para las 19:05 en el estadio Gasmart y en el que se repartir\u00e1n cuatro mil calcoman\u00edas a los primeros en ingresar al inmueble.<\/p>\n<p>En la lomita trabajar\u00e1n ma\u00f1ana Walter Silva (1-0; 3.77) por los locales y Marlon Arias (0-2; 10.45) por el cuadro de Oaxaca.<\/p>\n<p>Pizarra<br \/>\nEquipo\t123\t456\t789\tC     H     E<br \/>\nOaxaca\t\t010\t102\t310\t8    11    0<br \/>\nTijuana\t\t000\t000\t200\t2     3     2<br \/>\nPitcher ganador:\tAlejandro Soto (1-1)<br \/>\nPitcher derrotado:\tTerance Marin (1-1)<br \/>\nSalvamento:\tNo hubo<br \/>\nCuadrangulares:\t(Oax) Mario Valenzuela 2()<br \/>\n\t\t\t(Tij) Miguel Olivo (4)<br \/>\nEstadio:\tGasmart<br \/>\nAsistencia:\t5 mil 702 aficionados<br \/>\nDuraci\u00f3n:\t2 horas y 57 minutos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miguel Olivo bate\u00f3 cuadrangular de dos carreras, pero los Toros de Tijuana reaccionaron tarde y cayeron 2-8 ante Guerreros de Oaxaca, al abrir la serie en el estadio Gasmart.<\/p>\n","protected":false},"author":1,"featured_media":5195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[],"class_list":["post-5194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=5194"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5194\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/5195"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=5194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=5194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=5194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}