{"id":5167,"date":"2015-04-18T00:00:00","date_gmt":"2015-04-18T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2015\/04\/18\/sufren-toros-de-tijuana-reves-en-tabasco\/"},"modified":"2015-04-18T00:00:00","modified_gmt":"2015-04-18T07:00:00","slug":"sufren-toros-de-tijuana-reves-en-tabasco","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/sufren-toros-de-tijuana-reves-en-tabasco\/2015\/04\/","title":{"rendered":"Sufren Toros de Tijuana rev\u00e9s en Tabasco"},"content":{"rendered":"<p><strong>TIJUANA, Baja California (TorosdeTijuana.com-Armando Esquivel) 17 de abril del 2015. &#8211; <\/strong>Los Toros de Tijuana no pudieron descifrar los lanzamientos de C\u00e9sar Valdez y cayeron 2-6 al abrir la serie contra Olmecas de Tabasco, en el estadio Centenario del 27 de Febrero.<\/p>\n<p>Fue la segunda derrota consecutiva para los tijuanenses, sin embargo se mantienen como l\u00edderes de la Zona Norte y como el mejor equipo de toda la Liga Mexicana de B\u00e9isbol, al mostrar r\u00e9cord de 9-3.<\/p>\n<p>El diestro dominicano colg\u00f3 ocho argollas con apenas tres hits, ponch\u00f3 a nueve y s\u00f3lo regal\u00f3 un pasaporte, en lo que fue su segunda victoria de la campa\u00f1a.<\/p>\n<p>Los due\u00f1os del patio no se anduvieron por las ramas al tomar la delantera desde el primer acto con la velocidad de Luis Durango, quien toc\u00f3 la bola para embasarse, luego se rob\u00f3 la intermedia para llegar a la tercera base con toque de sacrificio del tijuanense Daniel N\u00fa\u00f1ez y anot\u00f3 con elevado de sacrificio de Jos\u00e9 Castillo.<\/p>\n<p>Para el tercer acto los dirigidos por Alfonso \u201cHouston\u201d Jim\u00e9nez repitieron la dosis con otro toque del paname\u00f1o Luis Durango para llegar a primera y luego de que N\u00fa\u00f1ez se volviera a sacrificar con toquecito, fue remolcado con doblete de Jos\u00e9 Castillo y el propio venezolano timbr\u00f3 con imparable al central de Wilson Batista.<\/p>\n<p>Ya en la cuarta tanda los Olmecas sumaron una m\u00e1s con triple de Luis Durango y doble de Daniel N\u00fa\u00f1ez para poner la pizarra 4-0.<\/p>\n<p>Los \u201ccabezones\u201d aseguraron la victoria en la s\u00e9ptima entrada al pisar el pent\u00e1gono en dos ocasiones m\u00e1s, gracias al doblete de Wilson Batista con el que anotaron el corredor emergente Iv\u00e1n Bellazet\u00edn y Donell Linares.<\/p>\n<p>Fue hasta el noveno cap\u00edtulo cuando los Toros de Tijuana se quitaron la blanqueada ya sobre los relevistas, al fabricar sus dos carreras, producto de sencillos productores de Ad\u00e1n Mu\u00f1oz y C.J. Retherford, para que anotaran Rom\u00e1n Pe\u00f1a y Eloy Guti\u00e9rrez de manera respectiva.<\/p>\n<p>C\u00e9sar Valdez fue el ganador con una magistral actuaci\u00f3n en la que no permiti\u00f3 libertades a la poderosa ofensiva de Toros de Tijuana y con su labor lleg\u00f3 a 21 entradas de labor con s\u00f3lo una carrera limpia tolerada.<\/p>\n<p>En su auxilio el zurdo Leobardo Moreno fue el responsable de las dos anotaciones de los Toros de Tijuana y terminaron el juego Ra\u00fal Carrillo y Luis Ignacio Ayala.<br \/>\nPor la escuadra que dirige Eddie D\u00edaz abri\u00f3 y perdi\u00f3 Leonardo Gonz\u00e1lez en dos entradas y un tercio de tres carreras, seis imparables, con relevos de Rodolfo Gonz\u00e1lez y Fernando Villalobos.<\/p>\n<p>Ma\u00f1ana se desarrollar\u00e1 el segundo juego de la serie y est\u00e1n anunciados para lanzar Jos\u00e9 Contreras (1-0, 2.45) por los Toros de Tijuana y \u00c1ngel Araiza (0-0, 6.48) por los tabasque\u00f1os.<\/p>\n<p>Pizarra<br \/>\nEquipo 123 456 789 C H E<br \/>\nTijuana 000 000 002 2 7 1<br \/>\nTabasco 102 100 20x 6 15 0<br \/>\nPitcher ganador: C\u00e9sar Valdez (2-0)<br \/>\nPitcher derrotado: Leonardo Gonz\u00e1lez (0-1)<br \/>\nSalvamento: Luis Ignacio Ayala (2)<br \/>\nEstadio: Centenario del 27 de febrero<br \/>\nAsistencia: 5 mil 345 aficionados<br \/>\nDuraci\u00f3n: 2 horas con 43 minutos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Toros de Tijuana no pudieron descifrar los lanzamientos de C\u00e9sar Valdez y cayeron 2-6 al abrir la serie contra Olmecas de Tabasco, en el estadio Centenario del 27 de Febrero<\/p>\n","protected":false},"author":1,"featured_media":5168,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[],"class_list":["post-5167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=5167"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/5168"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=5167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=5167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=5167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}