{"id":5155,"date":"2015-04-15T00:00:00","date_gmt":"2015-04-15T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2015\/04\/15\/abren-toros-de-tijuana-gira-con-triunfo\/"},"modified":"2015-04-15T00:00:00","modified_gmt":"2015-04-15T07:00:00","slug":"abren-toros-de-tijuana-gira-con-triunfo","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/abren-toros-de-tijuana-gira-con-triunfo\/2015\/04\/","title":{"rendered":"Abren Toros de Tijuana gira con triunfo"},"content":{"rendered":"<p><strong>TIJUANA, Baja California (TorosdeTijuana.com-Armando Esquivel) 14 de abril del 2015. &#8211; <\/strong>Los Toros de Tijuana ligaron su tercer triunfo y arrancaron con el pie derecho la serie inter zonas, al vencer hoy por 4-1 a Rojos del \u00c1guila de Veracruz en el estadio Deportivo Beto \u00c1vila.<\/p>\n<p>La victoria no fue f\u00e1cil para el conjunto fronterizo, ya que se fueron en blanco en los primeros seis cap\u00edtulos, cinco de ellos ante la serpentina del abridor \u00d3scar Verdugo, pero en la s\u00e9ptima entrada le cayeron a los relevos y lograron remontar para sumar su octavo triunfo de la naciente temporada 2015 de la Liga Mexicana de B\u00e9isbol (LMB).<\/p>\n<p>Con el resultado favorable, los Toros de Tijuana se consolidan como el l\u00edder de la Zona Norte, al sacar dos juegos de ventaja a los Acereros del Norte que ayer cayeron en casa ante Piratas de Campeche y adem\u00e1s, son el mejor equipo de toda la LMB, al acumular r\u00e9cord de 8-1.<\/p>\n<p>En el duelo de hoy, los porte\u00f1os se pusieron en el marcador en el fondo del primer episodio cuando, con un out, Eder Salcedo dio sencillo al izquierdo, avanz\u00f3 a la intermedia con base por bolas a Jos\u00e9 Guadalupe Ch\u00e1vez y timbr\u00f3 con imparable productor del estadounidense Ian Gac al jard\u00edn derecho.<\/p>\n<p>La entrada de la suerte sonri\u00f3 a los dirigidos por Eddie D\u00edaz que se quitaron la blanqueada y remontaron con racimo de tres carreras con doblete productor de Luis Mauricio Su\u00e1rez para que anotara H\u00e9ctor Hern\u00e1ndez, luego el tijuanense \u00d3scar Robles toc\u00f3 la pelota al ver a Adelaido Mart\u00ednez jugando muy atr\u00e1s para lograr embasarse y remolcar a Eduardo Arredondo.<\/p>\n<p>Miguel Olivo produjo la tercera rayita de esa entrada con imparable al prado derecho permitiendo que Luis Mauricio Su\u00e1rez pisara el pent\u00e1gono y decretara el 3-1 parcial en los cartones.<\/p>\n<p>La \u201cestampida\u201d sum\u00f3 su cuarta anotaci\u00f3n en la parte alta del noveno acto, cuando Eduardo Arredondo dio sencillo y anot\u00f3 luego de un error en una revirada y par de lanzamientos descontrolados del relevista V\u00edctor Marte.<\/p>\n<p>En la lomita circularon por los Toros el abridor Alejandro Mart\u00ednez, quien se fue sin decisi\u00f3n tras cinco entradas de una carrera, cuatro hits, tres ponches y una base, con relevo del ganador Francisco Liz\u00e1rraga, Jos\u00e9 Luis Garc\u00eda, Rafael D\u00edaz, Dennys Reyes que sac\u00f3 la octava tanda en orden y con dos ponches.<\/p>\n<p>Liz\u00e1rraga se apunt\u00f3 su segundo triunfo de la campa\u00f1a, al retirar la sexta entrada en blanco con un hit y una base por bolas.<\/p>\n<p>Ram\u00f3n Ram\u00edrez trabaj\u00f3 la novena tanda para su cuarto salvamento del a\u00f1o, departamento en el que es el mejor de la liga.<\/p>\n<p>Por los Rojos del \u00c1guila trabajaron en el mont\u00edculo el tijuanense \u00d3scar Verdugo con cinco cap\u00edtulos en blanco y de s\u00f3lo dos hits, cinco pasaportes y cuatro chocolates, con auxilio de Omar V\u00e1zquez, Norman Elenes, el derrotado Jos\u00e9 Meraz, quien en una entrada toler\u00f3 las tres carreras con cuatro hits.<\/p>\n<p>Le sigui\u00f3 el dominicano Esmailin Caridad y termin\u00f3 V\u00edctor Marte con una carrera.<\/p>\n<p>Las acciones se reanudan ma\u00f1ana mi\u00e9rcoles a las 17:30 horas (horario de Tijuana) con el segundo choque de esta serie inter zonas que tendr\u00e1 como protagonistas en la lomita a Terence Marin (0-0) por los Toros e Ignacio Monta\u00f1o (1-0) por los jarochos.<\/p>\n<p>Pizarra<br \/>\nEquipo 123 456 789 C H E<br \/>\nTijuana 000 000 301 4 10 1<br \/>\nVeracruz 000 100 00x 1 6 2<br \/>\nPitcher ganador: Fernando Liz\u00e1rraga (2-1)<br \/>\nPitcher derrotado: Jos\u00e9 Meraz (0-1)<br \/>\nSalvamento: Ram\u00f3n Ram\u00edrez (3)<br \/>\nCuadrangulares: No hubo<br \/>\nEstadio: Deportivo Beto \u00c1vila<br \/>\nAsistencia: 2 mil 690 aficionados<br \/>\nDuraci\u00f3n: 3 horas y 32 minutos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Toros de Tijuana ligaron su tercer triunfo y arrancaron con el pie derecho la serie inter zonas, al vencer hoy por 4-1 a Rojos del \u00c1guila de Veracruz<\/p>\n","protected":false},"author":1,"featured_media":5156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[],"class_list":["post-5155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=5155"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5155\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/5156"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=5155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=5155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=5155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}