{"id":5123,"date":"2015-04-02T00:00:00","date_gmt":"2015-04-02T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2015\/04\/02\/definen-toros-de-tijuana-roster-para-iniciar-temporada-2015\/"},"modified":"2015-04-02T00:00:00","modified_gmt":"2015-04-02T07:00:00","slug":"definen-toros-de-tijuana-roster-para-iniciar-temporada-2015","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/definen-toros-de-tijuana-roster-para-iniciar-temporada-2015\/2015\/04\/","title":{"rendered":"Definen Toros de Tijuana roster para iniciar temporada 2015"},"content":{"rendered":"<p><strong>TIJUANA. Baja California (TorosdeTijuana.com-Armando Esquivel) 1 de abril del 2015 &#8211; <\/strong>Eddie D\u00edaz dio a conocer hoy el roster final de treinta jugadores con el que los Toros de Tijuana arrancar\u00e1n la temporada 2015 de la Liga Mexicana de Beisbol (LMB).<\/p>\n<p>El documento que ya fue enviado a las oficinas de la LMB en la ciudad de M\u00e9xico, tiene a tres receptores, ocho jugadores de cuadro, cinco jardineros y catorce serpentineros, quienes fueron los elegidos luego de que el martes finalizara la fase de pretemporada.<\/p>\n<p>Con este pelot\u00f3n de tres decenas de peloteros, la escuadra que dirige el manejador dominicano, enfrentar\u00e1 a los Diablos Rojos del M\u00e9xico despu\u00e9s de la ceremonia inaugural de la LMB que se desarrollar\u00e1 en el estadio Fray Nano.<\/p>\n<p>*Receptores<br \/>\nAd\u00e1n Mu\u00f1oz<br \/>\nMiguel Olivo<br \/>\nOmar Renter\u00eda<\/p>\n<p>*Jugadores de cuadro<br \/>\nBernardo Heras<br \/>\nC.J. Retherford<br \/>\nFernando Valenzuela<br \/>\nH\u00e9ctor Hern\u00e1ndez<br \/>\nJes\u00fas Valenzuela<br \/>\nMiguel Torrero<br \/>\n\u00d3scar Robles<br \/>\nAbel Mart\u00ednez<\/p>\n<p>*Jardineros<br \/>\nEduardo Arredondo<br \/>\nEloy Guti\u00e9rrez<br \/>\nEnrique Trujillo<br \/>\nLuis Mauricio Su\u00e1rez<br \/>\nRom\u00e1n Pe\u00f1a<\/p>\n<p>*Lanzadores<br \/>\nAlejandro Mart\u00ednez<br \/>\nDennis Reyes<br \/>\nFrancisco Lizarraga<br \/>\nFernando Villalobos<br \/>\nMiguel Ruiz<br \/>\nJes\u00fas Garc\u00eda<br \/>\nLeonardo Gonz\u00e1lez<br \/>\nRodolfo Gonz\u00e1lez<br \/>\nJos\u00e9 Contreras<br \/>\nJos\u00e9 Luis Garc\u00eda<br \/>\nMario Mendoza<br \/>\nRafael D\u00edaz<br \/>\nRam\u00f3n Ram\u00edrez<br \/>\nWalter Silva<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eddie D\u00edaz dio a conocer hoy el roster final de treinta jugadores con el que los Toros de Tijuana arrancar\u00e1n la temporada 2015 de la Liga Mexicana de Beisbol (LMB).<\/p>\n","protected":false},"author":1,"featured_media":5124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[],"class_list":["post-5123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=5123"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/5124"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=5123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=5123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=5123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}