{"id":5106,"date":"2015-03-29T00:00:00","date_gmt":"2015-03-29T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2015\/03\/29\/cierran-toros-entrenamiento-primaveral-con-victoria\/"},"modified":"2015-03-29T00:00:00","modified_gmt":"2015-03-29T07:00:00","slug":"cierran-toros-entrenamiento-primaveral-con-victoria","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/cierran-toros-entrenamiento-primaveral-con-victoria\/2015\/03\/","title":{"rendered":"Cierran Toros entrenamiento primaveral con victoria"},"content":{"rendered":"<p><strong>TUCSON, Arizona (TorosdeTijuana.com-Rodolfo Gonz\u00e1lez) 28 de marzo del 2015 &#8211; <\/strong>Los Toros de Tijuana cerraron con victoria ante los Rojos del \u00c1guila su participaci\u00f3n en el entrrenamiento primaveral que se lleva a cabo en complejo Kino Sports de Tucson, Arizona.<\/p>\n<p>Fue una r\u00e1pida ofensiva que mostraron los de Tijuana desde el primer episodio, donde Enrique Trujillo logr\u00f3 alcanzar la intermedia r\u00e1pidamente para despu\u00e9s ser tra\u00eddo al plato por Miguel Torrero en lo que ser\u00eda la primera anotaci\u00f3n del encuentro.<\/p>\n<p>Miguel Ru\u00edz mantuvo sobre la raya al rival durante par de entradas; despu\u00e9s tomaron el mont\u00edculo en el tercer episodio Francisco Lizarraga y Miguel Ram\u00edrez, en el cuarto los del puerto lograr\u00edan poner tablas la pizarra con un cuadrangular solitario de Ian Gac.<\/p>\n<p>En la parte baja del mismo rollo lleg\u00f3 la respuesta de los fronterizos con un imparable de Fernando Valenzuela Jr. para devolver la ventaja a los fronterizos, ahora de 2 carreras por 1.<\/p>\n<p>La \u00faltima carrera de los Toros llegar\u00eda en el octavio episodio tras una rola de Jes\u00fas Valenzuela para impulsar a Isaac Rodr\u00edguez a la registradora y as\u00ed sellar el marcador 3 por 1.<\/p>\n<p>Tuvieron actividad retirando los \u00faltimos cuatro episodios del encuentro los lanzadores: Esteban Hern\u00e1ndez, Rudy Gonz\u00e1lez, Jose Mar\u00eda Albertos y Ram\u00f3n Ram\u00edrez.<\/p>\n<p>Los Toros de Tijuana concluyeron su participaci\u00f3n en el entrenamiento primaveral del complejo Kino Sports de Tucson Arizona con r\u00e9cord de 6 ganados, 5 derrotas y 3 empates. Su pr\u00f3ximo y \u00faltimo encuentro de pretemporada ser\u00e1 ante Toritos de Tijuana el 31 de marzo en el estadio Gasmart en punto de las 19:00 horas. La entrada ser\u00e1 libre para el p\u00fablico en general.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Toros de Tijuana cerraron con victoria ante los Rojos del \u00c1guila su participaci\u00f3n en el entrrenamiento primaveral que se lleva a cabo en complejo Kino Sports de Tucson, Arizona.<\/p>\n","protected":false},"author":2,"featured_media":5107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-5106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=5106"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/5107"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=5106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=5106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=5106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}