{"id":5017,"date":"2015-03-03T00:00:00","date_gmt":"2015-03-03T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2015\/03\/03\/madrugan-aficionados-por-boletos-inaugurales-en-tijuana\/"},"modified":"2015-03-03T00:00:00","modified_gmt":"2015-03-03T07:00:00","slug":"madrugan-aficionados-por-boletos-inaugurales-en-tijuana","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/madrugan-aficionados-por-boletos-inaugurales-en-tijuana\/2015\/03\/","title":{"rendered":"Madrugan aficionados por boletos inaugurales en Tijuana"},"content":{"rendered":"<p><strong>TIJUANA, Baja California (TorosdeTijuana.com-Rodolfo Gonz\u00e1lez) 2 de Marzo del 2015 &#8211; <\/strong>Con gran entusiasmo se presentaron hoy en el Estadio Gasmart decenas de aficionados a los Toros de Tijuana, quienes desde temprana hora, hicieron fila para adquirir sus boletos y no perderse su lugar en la gran fiesta de inauguraci\u00f3n pactada para el pr\u00f3ximo domingo 5 de Abril.<\/p>\n<p>Entre los &#8220;torofans&#8221; se encontraba Melissa Martinez, quien fue la primera persona en llegar al inmueble y su esfuerzo tuvo recompensa, ya que pudo adquirir los pases para ella y su familia.<\/p>\n<p>&#8220;Llegu\u00e9 a las 6:40 de la ma\u00f1ana y ya tengo mis boletos; invito a la afici\u00f3n a que se anime, se va a poner muy bueno el ambiente; adem\u00e1s del buen espect\u00e1culo tambi\u00e9n tenemos muchas ganas de ver a Nortec, el grupo tijuanense por excelencia&#8221;, coment\u00f3 Melissa.<\/p>\n<p>Los boletos est\u00e1n disponibles en dos localidades, ambos con precios muy accesibles para los fieles aficionados.<\/p>\n<p>El primero de ellos tiene un costo de 150 pesos, el cual tendr\u00e1 acceso a la zona central del estadio. Tambi\u00e9n se encuentra en venta la secci\u00f3n lateral por 100.<\/p>\n<p>La cita ser\u00e1 el 5 de abril, cuando los actuales campeones Diablos Rojos visiten la casa de los Toros de Tijuana. Las puertas del estacionamiento se encontrar\u00e1n abiertas a partir de las 12:00 horas, mientras que los accesos al estadio quitar\u00e1n sus cerraduras tres horas despu\u00e9s, para as\u00ed comenzar con la gran fiesta a partir desde las 18:00 horas, en lo que se espera sea una gran celebraci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con gran entusiasmo se presentaron hoy en el Estadio Gasmart decenas de aficionados a los Toros de Tijuana, quienes desde temprana hora, hicieron fila para adquirir sus boletos y no perderse su lugar en la gran fiesta de inauguraci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":5018,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[],"class_list":["post-5017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=5017"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/5018"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=5017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=5017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=5017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}