{"id":5004,"date":"2015-02-25T00:00:00","date_gmt":"2015-02-25T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2015\/02\/25\/trabaja-oscar-robles-en-casa\/"},"modified":"2015-02-25T00:00:00","modified_gmt":"2015-02-25T07:00:00","slug":"trabaja-oscar-robles-en-casa","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/trabaja-oscar-robles-en-casa\/2015\/02\/","title":{"rendered":"Trabaja \u00d3scar Robles en casa"},"content":{"rendered":"<p><strong>TIJUANA, Baja  California (TorosdeTijuana.com-Armando Esquivel) 24 de febrero del 2015 &#8211; <\/strong>El tijuanense \u00d3scar Robles vivi\u00f3 el martes su primera jornada de trabajo en su ciudad natal, al unirse a la pretemporada que los Toros de Tijuana realizan en el estadio Gasmart.<\/p>\n<p>El tercera base que el a\u00f1o pasado jug\u00f3 con los Guerreros de Oaxaca, se puso a las \u00f3rdenes del manejador dominicano Eddie D\u00edaz y realiz\u00f3 su primera pr\u00e1ctica completa junto a sus nuevos  compa\u00f1eros que lo acompa\u00f1ar\u00e1n en esta nueva aventura de jugar b\u00e9isbol frente a su familia.<\/p>\n<p>\u201cEstoy muy contento de iniciar ya hoy mi etapa como jugador de Toros de Tijuana; fueron muchos a\u00f1os jugando alejado de mi casa y de mi familia y hoy ya estoy aqu\u00ed en Tijuana y con mi gente; listo para prepararme para este compromiso tan grande\u201d, coment\u00f3 Robles a los medios que ayer se presentaron a entrevistarlo.<br \/>\nAlgo que emocion\u00f3 mucho al tercera base que jug\u00f3 en Grandes Ligas con los Padres y Dodgers, fue el poder llevar a sus hijos a la escuela y de ah\u00ed encaminarse a su trabajo, algo que nunca hab\u00eda podido hacer.<\/p>\n<p>\u201cFue algo muy emocionante poder ir a la escuela y luego venirme a trabajar aqu\u00ed al estadio; eso es algo muy especial, poder estar con mi familia\u201d, agreg\u00f3.<\/p>\n<p>Robles trabaj\u00f3 en el primer grupo que tom\u00f3 la pr\u00e1ctica de bateo, junto a su \u201cpaisano\u201d Rom\u00e1n Pe\u00f1a Zonta, Luis Mauricio Su\u00e1rez y Ad\u00e1n Mu\u00f1oz.<\/p>\n<p><b>Llega Jos\u00e9 Contreras<\/b><\/p>\n<p>Jos\u00e9 Contreras, el \u201cRey del ponche\u201d la temporada pasada, se report\u00f3 a los entrenamientos de los Toros de Tijuana, siempre con su sencillez y su buena vibra que logra irradiar al resto del plantel.<\/p>\n<p>\u201cYa estamos aqu\u00ed para ponernos listos para esta temporada; no queremos que pase lo del a\u00f1o pasado y buscamos hacer un buen trabajo de pretemporada para llegar en mucho mejor forma para el arranque de la campa\u00f1a\u201d, coment\u00f3 Contreras.<\/p>\n<p>Con un buen clima, el grupo de jugadores supera los cuarenta, ya que ocho j\u00f3venes prospectos se unieron desde el lunes a los trabajos del equipo grande, destacando entre ellos el tijuanense Bernardo Heras, quien busca un lugar en el equipo para poder jugar en la segunda base.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El tijuanense \u00d3scar Robles vivi\u00f3 el martes su primera jornada de trabajo en su ciudad natal, al unirse a la pretemporada que los Toros de Tijuana realizan en el estadio Gasmart.<\/p>\n","protected":false},"author":1,"featured_media":5005,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[],"class_list":["post-5004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=5004"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/5004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/5005"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=5004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=5004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=5004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}