{"id":4967,"date":"2015-02-03T00:00:00","date_gmt":"2015-02-03T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2015\/02\/03\/mexico-debuta-con-victoria-ante-cuba-2\/"},"modified":"2015-02-03T00:00:00","modified_gmt":"2015-02-03T07:00:00","slug":"mexico-debuta-con-victoria-ante-cuba-2","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/mexico-debuta-con-victoria-ante-cuba-2\/2015\/02\/","title":{"rendered":"M\u00e9xico debuta con victoria ante Cuba"},"content":{"rendered":"<p><strong> &#8211; <\/strong>Walter Ibarra rompi\u00f3 un empate con sencillo productor al jard\u00edn derecho y Anthony V\u00e1zquez se combin\u00f3 con cuatro relevistas para espaciar apenas seis hits en el triunfo de M\u00e9xico por 2-1 sobre Cuba en el primer juego de la Serie del Caribe.<\/p>\n<p>El representativo isle\u00f1o de Pinar del R\u00edo se puso adelante al abrirse el cuarto acto, cuando Yulieski Gourriel fue golpeado y luego de robarse la intermedia anot\u00f3 con imparable al derecho de Frederich Cepeda.<\/p>\n<p>La igualada mexicana se dio en el fondo de la sexta ronda cuando Rico Noel fue golpeado, avanz\u00f3 a la intermedia con rolita de Maxwell Le\u00f3n  a la inicial y se posesion\u00f3 de la antesala en jugada de selecci\u00f3n a batazo de Eric Farris, para anotar en un intento fallido de los cubanos por hacer una doble matanza a batazo de Joey Meneses.<\/p>\n<p>La entrada de la suerte sonr\u00edo al cuadro mexicano, pues lograron tomar una ventaja que ya no perder\u00edan, sobre el relevo de Jonder Mart\u00ednez, quien se subi\u00f3 a la loma en sustituci\u00f3n del abridor Freddy \u00c1lvarez.<\/p>\n<p>La voz de ataque la dio Issmael Salas al tramitar pasaporte y avanzar a segunda con toque de sacrificio de Dave Sappelt. Con hombre en segunda y un out, el alto mando cubano llev\u00f3 al mont\u00edculo a Liv\u00e1n Moinelo para lanzarle al tijuanense \u00d3scar Robles, pero Benjam\u00edn Gil hizo su parte y mand\u00f3 a la caja de bateo a Walter Ibarra, quien respondi\u00f3 con el batazo de la victoria.<\/p>\n<p>En la lomita abri\u00f3 por M\u00e9xico Anthony V\u00e1zquez, quien se fue tras cinco entradas de una carrera y cinco imparables, contando con los eficaces relevos del ganador  Terrance Marin, H\u00e9ctor Daniel Rodr\u00edguez y rescate para \u00d3scar Villarreal.<\/p>\n<p>La derrota qued\u00f3 en el r\u00e9cord de Jonder Mart\u00ednez en auxilio del abridor Freddy \u00c1lvarez, quien tuvo una dominante ejecuci\u00f3n en seis tandas de apenas dos hits y una carrera.<\/p>\n<p>Para ma\u00f1ana el selectivo mexicano se medir\u00e1 al anfitri\u00f3n Puerto Rico en el horario estelar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Walter Ibarra rompi\u00f3 un empate con sencillo productor al jard\u00edn derecho y Anthony V\u00e1zquez se combin\u00f3 con cuatro relevistas para espaciar apenas seis hits en el triunfo de M\u00e9xico por 2-1 sobre Cuba en el 1er juego de la Serie del Caribe<\/p>\n","protected":false},"author":1,"featured_media":4966,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4967"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4966"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}