{"id":4963,"date":"2015-01-30T00:00:00","date_gmt":"2015-01-30T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2015\/01\/30\/la-aficion-de-toros-fundamental-para-oscar-robles\/"},"modified":"2015-01-30T00:00:00","modified_gmt":"2015-01-30T07:00:00","slug":"la-aficion-de-toros-fundamental-para-oscar-robles","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/la-aficion-de-toros-fundamental-para-oscar-robles\/2015\/01\/","title":{"rendered":"La afici\u00f3n de Toros fundamental para \u00d3scar Robles"},"content":{"rendered":"<p><strong>Culiac\u00e1n, Sin. (TorosdeTijuana | Edgar De Alba). &#8211; <\/strong>\u00d3scar Robles volver\u00e1 a representar a M\u00e9xico en una justa caribe\u00f1a y en esta ocasi\u00f3n lo har\u00e1 con los campeones 2015 de la Liga Mexicana del Pac\u00edfico (LMP), Tomateros de Culiac\u00e1n, que vencieron en 5 juegos a Charros de Jalisco en la Serie Final de la LMP.<\/p>\n<p> El \u201cHijo pr\u00f3digo de Tijuana\u201d dio declaraciones a la reportera Blanca R\u00edos Burgos de L\u00ednea Directa sobre su sentimientos de buscar el tricampeonato caribe\u00f1o en la Serie del Caribe 2015 celebrada en San Juan, Puerto Rico con M\u00e9xico y el tercero tambi\u00e9n para la organizaci\u00f3n de Tomateros, bajo las \u00f3rdenes del tambi\u00e9n tijuanense Benjam\u00edn Gil .<\/p>\n<p>Robles  Arenas dijo estar muy contento de que tanto su familia y la afici\u00f3n de Toros lo manden felicitar desde la frontera m\u00e1s visitada ya que la siguiente temporada estar\u00e1 vistiendo la franela tijuanense, \u201cEs un gusto estar en casa, mucha gente me ha estado felicitando por todos los medios posibles por el campeonato conseguido con Culiac\u00e1n y por qu\u00e9 no so\u00f1ar con un campeonato con Tijuana, que bien merecido lo tiene la afici\u00f3n de los Toros\u201d, coment\u00f3<\/p>\n<p>\u201cSabemos que el apoyo de la afici\u00f3n es importante, por eso uno tiene que seguir trabajando duro para mantenernos en un buen nivel y entregar los mejores resultados \u201c, agreg\u00f3 el \u201cAstro boy\u201d sobre su compromiso con la afici\u00f3n de Toros.<\/p>\n<p>El tijuanense sabe que el camino no ser\u00e1 f\u00e1cil, pero conf\u00eda en los movimientos hechos por la directiva para lograr un equipo competitivo en la temporada 2015 de Liga Mexicana de B\u00e9isbol (LMB), \u201cCuando regres\u00f3 Tijuana a la LMB no era un roster muy disminuido, pero el Sr. Uribe se ha encargado de hacer movimientos grandes, no ser\u00e1 una liga f\u00e1cil porque tambi\u00e9n los otros equipos se est\u00e1n armando fuerte, pero nos vamos a entregar para darle satisfacciones a la afici\u00f3n de Tijuana&#8221;.<\/p>\n<p>Tambi\u00e9n \u00d3scar Robles coment\u00f3 que le llena de alegr\u00eda defender la casaca mexicana defendiendo con Tomateros, \u201cAhora estamos reforzando a M\u00e9xico, pero esa misi\u00f3n no ser\u00e1 f\u00e1cil, como no fueron f\u00e1ciles las series contra Los Mochis, Mexicali y Jalisco, este equipo tiene hambre de triunfo y garra la misma que nos tiene aqu\u00ed\u201d, finalizo.<\/p>\n<p>El representativo mexicano estar\u00e1 debutando este lunes 2 de febrero, contra Cuba, a las 9:00 A.M (Tiempo del Pac\u00edfico)?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00d3scar Robles volver\u00e1 a representar a M\u00e9xico en una justa caribe\u00f1a y en esta ocasi\u00f3n lo har\u00e1 con los campeones 2015 de la Liga Mexicana del Pac\u00edfico (LMP), Tomateros de Culiac\u00e1n, que vencieron en 5 juegos a Charros de Jalisco<\/p>\n","protected":false},"author":1,"featured_media":4964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4963"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4964"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}