{"id":4930,"date":"2015-01-15T00:00:00","date_gmt":"2015-01-15T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2015\/01\/15\/un-reto-mas-para-dennys\/"},"modified":"2015-01-15T00:00:00","modified_gmt":"2015-01-15T07:00:00","slug":"un-reto-mas-para-dennys","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/un-reto-mas-para-dennys\/2015\/01\/","title":{"rendered":"Un reto m\u00e1s para Dennys"},"content":{"rendered":"<p><strong>TIJUANA, Baja California (TorosdeTijuana.com-Armando Esquivel) 14 de enero del 2015. &#8211; <\/strong>Para Dennys Reyes, lanzador relevista de Toros de Tijuana, cada temporada  de la Liga Mexicana de Beisbol (LMB) representa un reto importante y se prepara fuerte para cumplir con las expectativas que se derivan de su gran trayectoria.<\/p>\n<p>Reyes Velarde es un lanzador de 37 a\u00f1os que jug\u00f3 quince campa\u00f1as en las Grandes Ligas, repartidas entre los equipos de Rojos, Mellizos, Cardenales, Dodgers, Royals, Diamantes, Rockies, Piratas, Medias Rojas, Rangers y Padres, adem\u00e1s de participar en varias Series del Caribe y el Cl\u00e1sico Mundial de Beisbol.<\/p>\n<p>Es por eso, que el nacido en Higuera de Zaragoza, Sinaloa, tiene el compromiso de mostrarle a la afici\u00f3n su mejor trabajo cada que sube a la lomita ahora con los Toros de Tijuana.<\/p>\n<p>\u201cYa tengo 23 a\u00f1os como profesional y a\u00f1o con a\u00f1o es un reto debido a la categor\u00eda que uno tiene de haber jugado Grandes Ligas y haber tenido la suerte de haber estado en el mejor b\u00e9isbol del mundo; con todo eso viene una responsabilidad muy grande de cumplir con la expectativa de la gente que espera que yo haga las cosas bien\u201d, explic\u00f3 Reyes en entrevista en el estadio B-Air de Mexicali.<\/p>\n<p>El propio lanzador que debut\u00f3 en la LMB con los Diablos Rojos del M\u00e9xico en la temporada 1993, sabe que la clave de su \u00e9xito ha sido el trabajo diario, la disciplina, la dedicaci\u00f3n y la fuerza de voluntad para ir cumpliendo con cada uno de los objetivos trazados.<\/p>\n<p>\u201cMi objetivo ahorita es mantenerme sano, trabajar muy fuerte como siempre lo he hecho y poner mi granito de arena cada vez que me pongan a lanzar y con eso ayudar al equipo a ganar.<\/p>\n<p>El serpentinero zurdo estuvo a pr\u00e9stamo con los Toros de Tijuana la temporada pasada y recopil\u00f3 n\u00fameros de 1-1 en ganados y perdidos, con efectividad de 2.73 en 36 juegos, con cinco salvamentos, siete pasaportes y 25 ponches.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para Dennys Reyes, lanzador relevista de Toros de Tijuana, cada temporada  de la Liga Mexicana de Beisbol (LMB) representa un reto importante y se prepara fuerte para cumplir con las expectativas que se derivan de su gran trayectoria.<\/p>\n","protected":false},"author":1,"featured_media":4931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4930"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4931"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}