{"id":4892,"date":"2014-12-22T00:00:00","date_gmt":"2014-12-22T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2014\/12\/22\/vencera-plazo-para-mantener-butacas\/"},"modified":"2014-12-22T00:00:00","modified_gmt":"2014-12-22T07:00:00","slug":"vencera-plazo-para-mantener-butacas","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/vencera-plazo-para-mantener-butacas\/2014\/12\/","title":{"rendered":"Vencer\u00e1 plazo para mantener butacas"},"content":{"rendered":"<p><strong>TIJUANA, Baja California (TorosdeTijuana.com &#8211; Armando Esquivel) 22 de diciembre del 2014 &#8211; <\/strong>S\u00f3lo diez d\u00edas le restan a los abonados del 2014 para mantener su misma butaca de cara a la pr\u00f3xima campa\u00f1a de los Toros de Tijuana en la Liga Mexicana de Beisbol (LMB).<\/p>\n<p>Luis Gajardo, gerente comercial del club tijuanense dijo que desde el 28 de noviembre que inici\u00f3 la venta del Torobono 2015 se anunci\u00f3 un plazo de poco m\u00e1s de un mes para los abonados que la temporada pasada pudieran mantener la misma butaca.<\/p>\n<p>\u201cA partir del primero de enero todas las butacas que no fueron confirmadas por los abonados del 2014 quedar\u00e1n libres y podr\u00e1n ser tomadas por cualquier comprador; hasta el momento m\u00e1s de la mitad han pasado a renovar su abono, sin embargo quiero recordarles a los que faltan por venir ac\u00e1 al Toroshop que s\u00f3lo les quedan diez d\u00edas si quieren mantener sus mismo asientos\u201d, coment\u00f3 Gajardo.<\/p>\n<p>El Torobono 2015 cuenta con cuatro paquetes diferentes con costos de 499 para el B\u00e1sico, 1,999 el Cl\u00e1sico, 2,499 para el Plus y 12,999 en la modalidad del VIP.<\/p>\n<p>Los tres \u00faltimos incluyen gratis un viaje redondo a cualquier destino nacional, adem\u00e1s la entrada a los 58 juegos de locales incluyendo la ceremonia inaugural, una butaca personalizada y una casaca edici\u00f3n especial (s\u00f3lo para el Plus y VIP) s\u00f3lo para abonados.<\/p>\n<p>La venta del Torobono 2015 con estas caracter\u00edsticas finalizar\u00e1 el 28 de febrero del 2015.<\/p>\n<p>Los Toros de Tijuana inician la temporada 2015 el 3 de abril con una visita a los Diablos Rojos del M\u00e9xico en el estadio Fray Nano y dos d\u00edas despu\u00e9s los actuales campeones pagar\u00e1n la visita en el estadio Gasmart a los dirigidos por el dominicano Eddie D\u00edaz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00f3lo  diez d\u00edas le restan a los abonados del 2014 para mantener su misma butaca de cara a la pr\u00f3xima campa\u00f1a de los Toros de Tijuana en la Liga Mexicana de Beisbol (LMB).<\/p>\n","protected":false},"author":2,"featured_media":4893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4892"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4893"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}