{"id":4863,"date":"2014-12-10T00:00:00","date_gmt":"2014-12-10T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2014\/12\/10\/asamblea-de-presidentes-de-la-lmb-en-san-diego-california\/"},"modified":"2014-12-10T00:00:00","modified_gmt":"2014-12-10T07:00:00","slug":"asamblea-de-presidentes-de-la-lmb-en-san-diego-california","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/asamblea-de-presidentes-de-la-lmb-en-san-diego-california\/2014\/12\/","title":{"rendered":"Asamblea de Presidentes de la LMB en San Diego, California"},"content":{"rendered":"<p><strong>San Diego, California (www.lmb.com.mx) 9 de diciembre.- &#8211; <\/strong>La Liga Mexicana de Beisbol llev\u00f3 a cabo su Asamblea de Presidentes en el marco de las Reuniones Invernales, las cuales tienen como sede la ciudad de San Diego, California.<\/p>\n<p>La sesi\u00f3n inici\u00f3 con una oraci\u00f3n a cargo de un representante de Baseball Chapel; a continuaci\u00f3n, hubo una pl\u00e1tica por parte de Erik Nilsen, director de Baseball Assistance Team (B.A.T.), organizaci\u00f3n avalada por las Grandes Ligas y dedicada a prestar servicios sociales a miembros de la familia del beisbol organizado, quienes tengan necesidades m\u00e9dicas, financieras o psicol\u00f3gicas.<\/p>\n<p>En el rubro deportivo, la LMB aprob\u00f3 que jugar\u00e1 con seis extranjeros por equipo en la pr\u00f3xima temporada. En el caso de los Delfines del Carmen, tendr\u00e1n que cumplir con la regla de novatos: los lanzadores deber\u00e1n completar al menos 50 innings, de manera combinada, y los bateadores tener cuando menos 100 apariciones al bat, tambi\u00e9n de manera combinada.<\/p>\n<p>Catorce organizaciones ratificaron a sus managers para el pr\u00f3ximo calendario, s\u00f3lo los Sultanes de Monterrey y los Broncos de Reynosa quedaron pendientes, el listado de timoneles es el siguiente:<\/p>\n<p>1.- Pericos de Puebla: Von Hayes.<br \/>\n2.- Delfines del Carmen: F\u00e9lix Ferm\u00edn.<br \/>\n3.- Diablos Rojos del M\u00e9xico: Miguel Ojeda.<br \/>\n4.- Leones de Yucat\u00e1n: Willie Romero.<br \/>\n5.- Rieleros de Aguascalientes: Marco Antonio Davalillo.<br \/>\n6.- Toros de Tijuana: Eddie D\u00edaz.<br \/>\n7.- Piratas de Campeche: Dan Firova.<br \/>\n8.- Guerreros de Oaxaca: Enrique Reyes.<br \/>\n9.- Tigres de Quintana Roo: Jerry Royster.<br \/>\n10.- Rojos del \u00c1guila de Veracruz: H\u00e9ctor Estrada.<br \/>\n11.- Acereros de Monclova: Homar Rojas.<br \/>\n12.- Vaqueros Laguna: Lino Rivera.<br \/>\n13.- Saraperos de Saltillo: Juan Francisco Rodr\u00edguez.<br \/>\n14.- Olmecas de Tabasco: Alfonso Jim\u00e9nez.<\/p>\n<p>El Club Broncos de Reynosa operar\u00e1 durante 2015 y se encuentra realizando las gestiones necesarias para celebrar nueve series en Reynosa y nueve en Nuevo Laredo, Tamaulipas.<\/p>\n<p>La oficina de la LMB present\u00f3 su reporte de estadios y entreg\u00f3 las observaciones a cada uno de los clubes para que \u00e9stos inicien con las obras de remodelaci\u00f3n y mejoramiento de terreno de juego, alumbrado, clubhouses, dugouts, gradas, \u00e1reas de comida y servicios sanitarios, entre otros.<\/p>\n<p>En la reuni\u00f3n se presentaron adelantos de las propuestas hechas por los empresarios de Chetumal, Quintana Roo; Le\u00f3n, Guanajuato; y Mazatl\u00e1n, Sinaloa, quienes est\u00e1n interesados en que estas ciudades ingresen a la LMB en caso de que haya una expansi\u00f3n en 2016.<\/p>\n<p>La LMB sigue trabajando en la planeaci\u00f3n de los festejos del 90 Aniversario.<\/p>\n<p>Asimismo, se inform\u00f3 de un patrocinio a nivel corporativo con la empresa Alamo, dedicada a la de renta de autos, la cual tendr\u00e1 presencia en todos los petos de los catchers durante las pr\u00f3ximas tres temporadas.<\/p>\n<p>La Asamblea fue presidida por el Consejo Directivo, encabezado por su presidente, Ing. Jos\u00e9 Maiz Garc\u00eda, debido a que el C.P. Plinio Escalante Bolio, presidente de la LMB, tuvo que regresar a M\u00e9rida, Yucat\u00e1n para atender asuntos personales relacionados con la salud de su esposa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Liga Mexicana de Beisbol llev\u00f3 a cabo su Asamblea de Presidentes en el marco de las Reuniones Invernales, las cuales tienen como sede la ciudad de San Diego, California.<\/p>\n","protected":false},"author":2,"featured_media":4864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4863"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4864"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}