{"id":4823,"date":"2014-11-08T00:00:00","date_gmt":"2014-11-08T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2014\/11\/08\/aumentara-el-nivel-de-competencia-en-lmb\/"},"modified":"2014-11-08T00:00:00","modified_gmt":"2014-11-08T07:00:00","slug":"aumentara-el-nivel-de-competencia-en-lmb","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/aumentara-el-nivel-de-competencia-en-lmb\/2014\/11\/","title":{"rendered":"Aumentar\u00e1 el nivel de competencia en LMB"},"content":{"rendered":"<p><strong>TIJUANA, Baja California (TorosdeTijuana.com-Armando Esquivel) 8 de noviembre del 2014. &#8211; <\/strong>Los presidentes de la Liga Mexicana de Beisbol (LMB) dieron un gran paso ayer para mejorar de manera considerable el nivel de competencia para la pr\u00f3xima temporada, al aprobarse una reglamentaci\u00f3n que permitir\u00e1 a los jugadores mexicanos nacidos en el extranjero, participar como peloteros nacionales sin ocupar plaza de for\u00e1neos.<\/p>\n<p>Los altos mandos de  los 16 equipos se reunieron durante dos d\u00edas para su Asamblea General Ordinaria en la ciudad de Oaxaca, donde se lograron varios acuerdos que beneficiar\u00e1n de manera directa a los aficionados al rey de los deportes del pa\u00eds.<\/p>\n<p>Alejandro Uribe Herrera, presidente ejecutivo de Toros de Tijuana, destac\u00f3 el pacto que ahorrar\u00e1 a los equipos plazas de for\u00e1neos en su roster, ya que ahora todos los jugadores mexicanos nacidos fuera del pa\u00eds no ser\u00e1n considerados como extranjeros.<\/p>\n<p>\u201cEso elevar\u00e1 mucho el nivel de la liga, ya que ahora mientras los peloteros tengan pasaporte mexicano podr\u00e1n ser tomados en cuenta como jugadores mexicanos y eso definitivamente mejorar\u00e1 el nivel de competencia en la liga, ya que los equipos ser\u00e1n m\u00e1s competitivos\u201d, explic\u00f3 el directivo del equipo tijuanense.<br \/>\nLos jugadores que re\u00fanan estas caracter\u00edsticas pasar\u00e1n a un \u201cdraft\u201d de donde cada equipo, por sorteo, elegir\u00e1 de acuerdo a su posici\u00f3n.<\/p>\n<p>Tambi\u00e9n en el \u201cc\u00f3nclave\u201d de la \u201cverde Antequera\u201d hubo \u201chumo blanco\u201d, pues el presidente Plinio Escalante recibi\u00f3 el voto de confianza para seguir cuando menos dos a\u00f1os m\u00e1s al frente del circuito veraniego.<\/p>\n<p>Otro tema muy importante para el futuro de la Liga Mexicana de Beisbol (LMB) fue el de la expansi\u00f3n y Uribe Herrera coment\u00f3 que las plazas que han mostrado inter\u00e9s han sido las de Mazatl\u00e1n y Chetumal, aunque tambi\u00e9n ha habido acercamientos con la intenci\u00f3n de llevar el b\u00e9isbol profesional de vuelta a Le\u00f3n.<\/p>\n<p>\u201cSe sigue considerando la expansi\u00f3n en la liga, pero siempre y cuando haya plazas que cumplan con todos los requisitos\u201d, agreg\u00f3.<\/p>\n<p>Durante las sesiones del viernes, tambi\u00e9n se dio la bienvenida al nuevo propietario de los Saraperos de Saltillo, as\u00ed como el anuncio de que en fechas pr\u00f3ximas se inspeccionar\u00e1n cada uno de los estadios y habr\u00e1 multas para aquellos que no cuenten con las especificaciones m\u00ednimas para los aficionados, medios y jugadores.<\/p>\n<p>La pr\u00f3xima reuni\u00f3n de presidentes de equipos de la LMB se dar\u00e1 en la convenci\u00f3n del b\u00e9isbol organizado que se celebrar\u00e1 en San Diego durante la primera semana de diciembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los presidentes de la Liga Mexicana de Beisbol (LMB) dieron un gran paso ayer para mejorar de manera considerable el nivel de competencia para la pr\u00f3xima temporada<\/p>\n","protected":false},"author":2,"featured_media":4824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4823"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4824"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}