{"id":4762,"date":"2014-10-19T00:00:00","date_gmt":"2014-10-19T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2014\/10\/19\/vistazo-a-la-liga-mexicana-del-pacifico\/"},"modified":"2014-10-19T00:00:00","modified_gmt":"2014-10-19T07:00:00","slug":"vistazo-a-la-liga-mexicana-del-pacifico","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/vistazo-a-la-liga-mexicana-del-pacifico\/2014\/10\/","title":{"rendered":"Vistazo a la Liga Mexicana del Pac\u00edfico"},"content":{"rendered":"<p><strong>TIJUANA, Baja California (TorosdeTijuana.com-Armando Esquivel) 19 de octubre &#8211; <\/strong>ROBLES JONRONEA EN DERROTA<\/p>\n<p>\u00d3scar Robles, flamante contrataci\u00f3n de los Toros de Tijuana para la temporada 2015 de la Liga Mexicana del Beisbol (LMB), conect\u00f3 ayer su primer cuadrangular de la campa\u00f1a, aunque los Tomateros de Culiac\u00e1n terminaron perdiendo 5-9 ante Charros de Jalisco en el estadio \u00c1ngel Flores, en acciones de la Liga Mexicana del Pac\u00edfico.<\/p>\n<p>El le\u00f1azo del tijuanense fue con un out por todo el jard\u00edn derecho, en la parte baja de la misma primera entrada, sobre los lanzamientos del lanzador Graham Godfrey (1-0), quien al final de cuentas fue el ganador del encuentro, pues el batazo del tijuanense fue el \u00fanico da\u00f1o que recibi\u00f3 en cinco entradas de labor.<\/p>\n<p>El rescate fue el segundo en la campa\u00f1a para Brian Broderick.<br \/>\nEn la ofensiva de Charros hubo tres hits de Marquez Smith, entre ellos un jonr\u00f3n solitario; adem\u00e1s, Jos\u00e9 Manuel Rodr\u00edguez se fue de 5-4 con tres dobletes y dos producidas; Japhet Amador con par de imparables y dos remolques, Amadeo Zazueta de 4-2 y Eduardo Arredondo, jugador de Toros en la LMB, se fue de 4-1.<\/p>\n<p>Por los \u201cguindas\u201d tambi\u00e9n hubo cuadrangular de Jorge V\u00e1zquez con un compa\u00f1ero a bordo.<\/p>\n<p>Alfredo Aceves (0-2) fue el pitcher derrotado en una corta y sufrida labor de tres entradas y dos tercios de once hits y seis carreras.<\/p>\n<p>\u00c1GUILAS VENCEN A CA\u00d1EROS<\/p>\n<p>Shane Peterson bate\u00f3 dos triples y produjo tres carreras para comandar el triunfo de \u00c1guilas de Mexicali por 5-1 sobre Ca\u00f1eros de Los Mochis en el estadio Casas Geo.<\/p>\n<p>El zurdo de Fallbrook, California, dio de tres bases en el segundo acto y para la sexta entrada se volvi\u00f3 a \u2018subir a la moto\u2019 para remolcar par de rayitas.<\/p>\n<p>Por los \u00c1guilas tambi\u00e9n hubo dos hits de Xorge Carrillo y en el centro del diamante los honores fueron para Edgar Osuna (1-0) en cinco cap\u00edtulos y un tercio de una carrera y cuatro imparables.<br \/>\nEn la ofensiva \u201cverde\u201d s\u00f3lo destac\u00f3 Juan Carlos Gamboa al apuntarse la solitaria anotaci\u00f3n de su equipo, al disparar batazo de cuatro esquinas.<\/p>\n<p>Santiago Guti\u00e9rrez  (0-2) carg\u00f3 con el rev\u00e9s en cinco episodios y dos tercios de cinco inatrapables y cuatro anotaciones.<\/p>\n<p>LUCE WALTER EN LA LOMA<\/p>\n<p>Walter Silva, jugador de Toros de Tijuana en la LMB, se apunt\u00f3 ayer su segunda victoria de la campa\u00f1a, en el triunfo de Venados de Mazatl\u00e1n por 8-5 sobre Naranjeros de Hermosillo en el estadio Sonora.<\/p>\n<p>Silva (2-0) disemin\u00f3 cinco hits, permiti\u00f3 dos carreras y ponch\u00f3 a cinco en cinco entradas y un tercio de labor y entre sus relevos tambi\u00e9n vio acci\u00f3n Jos\u00e9 Luis Garc\u00eda, otro jugador de Toros de Tijuana, quien se fue sin da\u00f1o y retir\u00f3 dos tercios.<\/p>\n<p>La otra cara de la moneda fue para Marcos Rivas al permitir cinco anotaciones en apenas un cap\u00edtulo y un tercio de trabajo. Jos\u00e9 Cobos, jugador de Toros de Tijuana, cubri\u00f3 las \u00faltimas dos entradas en relevo con un hit, una base por bolas y un ponche.<\/p>\n<p>En la ofensiva mazatleca el mexicalense Jes\u00fas Castillo de 4-3 con doblete, producida y dos anotadas; el tijuanense Rom\u00e1n Pe\u00f1a Zonta de 4-2 con doble, par de empujadas y una anotada y Ryan Schimpf con dos hits, uno de ellos de dos bases.<\/p>\n<p>Por los \u201cnaranjas\u201d Luis Alfonso Garc\u00eda la bot\u00f3 con uno en base, mientras que Carlos Alberto Gast\u00e9lum y Jorge Flores agregaron par de indiscutibles.<\/p>\n<p>MAYOS GANAN EN DUELO DE \u201cTRIBUS\u201d<\/p>\n<p>Chris Marrero y Luis Fonseca se fueron para la calle con dos en base y Jos\u00e9 Guadalupe Ch\u00e1vez la bot\u00f3 con uno a bordo, para comandar la victoria de Mayos de Navojoa por 10-5 sobre Yaquis de Ciudad Obreg\u00f3n, en el estadio Manuel \u201cCicl\u00f3n\u201d Echeverr\u00eda.<\/p>\n<p>Marrero la ech\u00f3 en la primera entrada y al final del juego acab\u00f3 con cinco carreras producidas, mientras que Fonseca dio su batazo en la segunda tanda y Ch\u00e1vez en la cuarta.<\/p>\n<p>Jon Weber tambi\u00e9n destac\u00f3 por los locales con par de dobletes.<\/p>\n<p>La causa vencida la defendieron Carlos Valencia con doblete de dos carreras y dos hits del tijuanense Agust\u00edn Murillo, Donald Lutz, Sergio Contreras y Said Guti\u00e9rrez.<\/p>\n<p>Gan\u00f3 Irving Jim\u00e9nez (1-1) en relevo y perdi\u00f3 el abridor Rolando Acosta (1-1) en tres entradas de tortura con ocho carreras y nueve hits.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00d3scar Robles, flamante contrataci\u00f3n de los Toros de Tijuana para la temporada 2015 de la Liga Mexicana del Beisbol (LMB), conect\u00f3 ayer su primer cuadrangular de la campa\u00f1a, aunque los Tomateros de Culiac\u00e1n terminaron perdiendo 5-9<\/p>\n","protected":false},"author":2,"featured_media":4763,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4762"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4763"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}