{"id":4758,"date":"2014-10-18T00:00:00","date_gmt":"2014-10-18T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2014\/10\/18\/10-cosas-que-no-sabias-de-oscar-robles\/"},"modified":"2014-10-18T00:00:00","modified_gmt":"2014-10-18T07:00:00","slug":"10-cosas-que-no-sabias-de-oscar-robles","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/10-cosas-que-no-sabias-de-oscar-robles\/2014\/10\/","title":{"rendered":"10 cosas que no sab\u00edas de \u00d3scar Robles"},"content":{"rendered":"<p><strong> &#8211; <\/strong>Oscar Robles fue drafteado en 1994 por los Astros de Houston en el tercer round y con la posici\u00f3n 80 general.<\/p>\n<p>*Robles fue elegido antes de peloteros como A.J. Pierzynski, Aaron Boone, Russell Branyan, Pl\u00e1cido Polanco, Brett Tomko, J.D Drew, Tim Hudson, Eric Gagne y Dave Roberts.<\/p>\n<p>*Despu\u00e9s de haber sido firmado por los Astros de Houston tras el draft de 1994, \u00d3scar utiliz\u00f3 parte del dinero que le dio el equipo texano por su firma, para comprar una pizarra electr\u00f3nica que se instal\u00f3 en la preparatoria Montgomery en Chula Vista, California, instituci\u00f3n en la que estudi\u00f3.<\/p>\n<p>*Su debut en Grandes Ligas con los Dodgers de Los \u00c1ngeles fue el 10 de mayo del 2005, un d\u00eda en el que en M\u00e9xico se celebra el D\u00eda de Las Madres y en su primer juego se fue en blanco en cuatro turnos contra los Cardenales en San Luis.<\/p>\n<p>*Su primer manejador en Grandes Ligas fue Jim Tracy con Dodgers de Los \u00c1ngeles.<\/p>\n<p>*El primer hit de Robles en Grandes Ligas fue el 12 de mayo del 2005 contra los lanzamientos de Chris Carpenter de Cardenales en San Luis.<\/p>\n<p>*En el primer partido que vio acci\u00f3n en el Petco Park de San Diego, un 23 de junio del 2005, \u00d3scar conect\u00f3 doblete y anot\u00f3 carrera en la octava entrada para un triunfo de Dodgers sobre Padres por 4-3. A su lado, jug\u00f3 ese d\u00eda el tambi\u00e9n mexicano Elmer Dessens.<\/p>\n<p>*El 4 de julio del 2005, Robles conect\u00f3 cinco hits en seis turnos contra los Rockies de Colorado en Coors Field.<\/p>\n<p>*El 19 de julio del 2005, \u00d3scar dispar\u00f3 el primer cuadrangular en su carrera, al conectar s\u00f3lido le\u00f1azo a un lanzamiento de Brett Myers de Filis de Filadelfia en el Citizens Bank Park.<\/p>\n<p>*En Tijuana, dos campos de b\u00e9isbol llevan su nombre; uno est\u00e1 ubicado en la Liga de Beisbol Infantil y Juvenil Municipal de Tijuana y el otro en la primaria Juan Escutia, escuela en la que estudio en Otay Universidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oscar Robles fue drafteado en 1994 por los Astros de Houston en el tercer round y con la posici\u00f3n 80 general&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4758"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4759"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}