{"id":4715,"date":"2014-09-30T00:00:00","date_gmt":"2014-09-30T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2014\/09\/30\/sandy-madera-es-el-jugador-mas-valioso-2014-de-la-lmb\/"},"modified":"2014-09-30T00:00:00","modified_gmt":"2014-09-30T07:00:00","slug":"sandy-madera-es-el-jugador-mas-valioso-2014-de-la-lmb","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/sandy-madera-es-el-jugador-mas-valioso-2014-de-la-lmb\/2014\/09\/","title":{"rendered":"Sandy Madera es el Jugador M\u00e1s Valioso 2014 de la LMB"},"content":{"rendered":"<p><strong>M\u00e9xico, D.F. (lmb.com.mx) 26 de septiembre. &#8211; <\/strong>Sandy Madera, de los Pericos de Puebla, es el Jugador M\u00e1s Valioso de la Liga Mexicana de Beisbol, con base en las votaciones de la prensa especializada.<\/p>\n<p>Madera, bateador designado de los poblanos, fue el Campe\u00f3n de Bateo del circuito con promedio de .403; asimismo, fue el tercer mejor productor de la liga con 98 remolcadas y el n\u00famero uno en porcentaje de embasamiento con .477.<\/p>\n<p>Su slugging fue el m\u00e1s alto de la LMB con .696 y termin\u00f3 en tercer lugar de cuadrangulares y carreras producidas del circuito con 26 y 98, respectivamente.<\/p>\n<p>Las carreras creadas por Madera para su equipo fue el m\u00e1s alto n\u00famero de la liga, dicha cifra se calcula con el promedio de embasamiento por el total de bases alcanzadas por hit, sobre turnos al bat m\u00e1s bases por bolas. As\u00ed, el dominicano aport\u00f3 poco m\u00e1s del 15% de las anotaciones totales de Pericos.<\/p>\n<p>En casa bate\u00f3 para .452, mientras en gira lo hizo para .357. Conforme avanz\u00f3 la temporada su promedio mejor\u00f3, en abril bate\u00f3 .371, en junio .433 y en agosto .483.<\/p>\n<p>Enfrentarlo en la quinta entrada fue un reto para los lanzadores, pues en ese inning fue m\u00e1s peligroso durante todo el a\u00f1o con promedio de .500, seis jonrones y 25 producidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sandy Madera, de los Pericos de Puebla, es el Jugador M\u00e1s Valioso de la Liga Mexicana de Beisbol, con base en las votaciones de la prensa especializada.<\/p>\n","protected":false},"author":2,"featured_media":4716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4715"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4716"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}