{"id":4688,"date":"2014-08-31T00:00:00","date_gmt":"2014-08-31T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2014\/08\/31\/diablos-rojos-campeon-de-la-zona-norte\/"},"modified":"2014-08-31T00:00:00","modified_gmt":"2014-08-31T07:00:00","slug":"diablos-rojos-campeon-de-la-zona-norte","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/diablos-rojos-campeon-de-la-zona-norte\/2014\/08\/","title":{"rendered":"Diablos Rojos, campe\u00f3n de la Zona Norte"},"content":{"rendered":"<p><strong>M\u00e9xico, D.F. (diablos.com.mx | Vania Ravelo), 30 de agosto. &#8211; <\/strong>\u00a0 \u00a0Con triunfo por pizarra de 5-3 sobre Sultanes de Monterrey, Diablos Rojos del M\u00e9xico se alz\u00f3 Campe\u00f3n de la Zona Norte de la Liga Mexicana de Beisbol este s\u00e1bado en el Estadio Monterrey. Los escarlata barrieron en la serie a los &#8216;Fantasmas Grises&#8217; y aseguraron el boleto para disputar la Serie Final.<\/p>\n<p>La artiller\u00eda local abri\u00f3 el ataque en la primera baja ante los env\u00edos de Marlon Arias. Con Ram\u00f3n R\u00edos y Chris Roberson en las esquinas, Agust\u00edn Murillo conect\u00f3 sencillo por el jard\u00edn izquierdo y remolc\u00f3 dos carreras para los norte\u00f1os.<\/p>\n<p>En la tercera alta, Diablos Rojos arm\u00f3 un ataque definitivo. Con un out en la pizarra, Ram\u00f3n Ur\u00edas y Juan Carlos &#8216;Haper&#8217; Gamboa recibieron bases consecutivas, despu\u00e9s, la casa se llen\u00f3 con elevado de Carlos Figueroa al prado central. Enseguida, apareci\u00f3 en la caja de bateo Sergio Omar Gast\u00e9lum, el experimentado pelotero encontr\u00f3 uno de los env\u00edos del abridor Jorge Luis Castillo, se vol\u00f3 la barda del jard\u00edn izquierdo y vaci\u00f3 las esquinas. El grand slam del sonorense sentenci\u00f3 la remontada roja que aderez\u00f3 el estadounidense Douglas Clark con un cuadrangular solitario. As\u00ed, los rojos rubricaron la victoria por 5-3 sobre los norte\u00f1os.<\/p>\n<p>De \u00faltima hora, Sultanes timbr\u00f3 la tercera en la novena entrada con producci\u00f3n de Ad\u00e1n Mu\u00f1oz.<\/p>\n<p>El abridor Marlon Arias se acredit\u00f3 la victoria en s\u00f3lida apertura de siete innings en los que espaci\u00f3 cuatro imparables, dos carreras limpias y concedi\u00f3 cuatro bases por bolas, a cambio de cuatro ponches.<\/p>\n<p>Juan Sandoval firm\u00f3 el salvamento en dos entradas de un hit, una carrera limpia y un ponche.<\/p>\n<p>Gast\u00e9lum fue el l\u00edder ofensivo en el triunfo rojo con su grand slam en la parte alta de la tercera entrada.<\/p>\n<p>El derrotado Jorge Luis Castillo lanz\u00f3 cinco entradas de cuatro imparables -incluidos dos jonrones-, cinco carreras limpias, cuatro pasaportes y cinco chocolates.<\/p>\n<p>Ahora, Diablos Rojos del M\u00e9xico espera rival para disputar la Serie Final a partir del 6 de septiembre ante la novena que resulte ganadora de la Serie de Campeonato de la Zona Sur en la que pelean Pericos de Puebla y Tigres de Quintana Roo. Este s\u00e1bado, los emplumados vencieron por pizarra de 19-4 a los felinos y la serie se empat\u00f3 a dos triunfos por club.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con triunfo por pizarra de 5-3 sobre Sultanes de Monterrey, Diablos Rojos del M\u00e9xico se alz\u00f3 Campe\u00f3n de la Zona Norte<\/p>\n","protected":false},"author":2,"featured_media":4689,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4688"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4689"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}