{"id":4666,"date":"2014-08-12T00:00:00","date_gmt":"2014-08-12T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2014\/08\/12\/toros-de-tijuana-y-leones-de-yucatan-trabajaran-en-invierno\/"},"modified":"2014-08-12T00:00:00","modified_gmt":"2014-08-12T07:00:00","slug":"toros-de-tijuana-y-leones-de-yucatan-trabajaran-en-invierno","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/toros-de-tijuana-y-leones-de-yucatan-trabajaran-en-invierno\/2014\/08\/","title":{"rendered":"Toros de Tijuana y Leones de Yucat\u00e1n trabajar\u00e1n en invierno"},"content":{"rendered":"<p><strong>Mexico, D.F. (TorosdeTijuana.com \u2013 Edgar De Alba) 12 de agosto. &#8211; <\/strong>Toros no se tomar\u00e1 ning\u00fan descanso en el invierno , ya que tendr\u00e1n convenio de trabajo con los renovados Leones de Yucat\u00e1n buscando que los j\u00f3venes prospectos de la novena fronteriza y melenuda sigu\u00e1n trabajando y puliendo sus habilidades.<\/p>\n<p>\u201cEs un hecho que estaremos trabajando espalda con espalda junto a Leones de Yucat\u00e1n en la Liga de Beisbol del Noroeste (LBN), con los Leones de Tecuala y  en la Academia de El Carmen, Nuevo Le\u00f3n con el combinado TIJ-YUC\u201d, tambi\u00e9n Valenzuela hizo hincapi\u00e9 en el tema de los j\u00f3venes peloteros en pleno desarrollo que en un futuro pueden estar debutando con la franela tijuanense.<\/p>\n<p>\u201cEl objetivo es mejorar en todas nuestras \u00e1reas de oportunidad que tengamos, con el an\u00e1lisis final veremos cu\u00e1les son nuestras prioridades y necesidades para luego  atacarlas\u201d, agreg\u00f3 Eduardo Valenzuela Guajardo.<\/p>\n<p>\u201cNos interesa mucho el mejorar nuestras reservas ya que ellos ser\u00e1n los futuros representantes de nuestro club\u201d finaliz\u00f3 el directivo de Tijuana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toros no se tomar\u00e1 ning\u00fan descanso en el invierno, ya que tendr\u00e1n convenio de trabajo con los renovados Leones de Yucat\u00e1n buscando que los j\u00f3venes prospectos de la novena fronteriza y melenuda sigu\u00e1n trabajando y puliendo habilidades.<\/p>\n","protected":false},"author":2,"featured_media":4667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4666"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4667"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}