{"id":4658,"date":"2014-08-10T00:00:00","date_gmt":"2014-08-10T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2014\/08\/10\/triunfo-tinto-en-sangre-de-toros\/"},"modified":"2014-08-10T00:00:00","modified_gmt":"2014-08-10T07:00:00","slug":"triunfo-tinto-en-sangre-de-toros","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/triunfo-tinto-en-sangre-de-toros\/2014\/08\/","title":{"rendered":"Triunfo tinto en sangre de Toros"},"content":{"rendered":"<p><strong>Aguascalientes, Ags (TorosdeTijuana.com \u2013 Edgar De Alba) 9 de agosto. &#8211; <\/strong>Con jonr\u00f3n solitario de Arturo Rodr\u00edguez en la octava alta y herm\u00e9ticos lanzamientos del zurdo Dennys Reyes, Toros de Tijuana logra quedarse con la serie en la doble cartelera al ganar en extrainnings 9-8 ante Rieleros de Aguascalientes en el Estadio Alberto Romo Ch\u00e1vez, con esto Toros sigue peleado por el comod\u00edn de la Zona Norte en la Liga Mexicana de Beisbol (LMB).<\/p>\n<p>Rieleros tom\u00f3 ventaja en el primer episodio con jonr\u00f3n de Willis Ota\u00f1ez llev\u00e1ndose a Iv\u00e1n Bellazetin por delante y poniendo la pizarra 2-0, despu\u00e9s Miguel Torrero con sencillo al izquierdo impuls\u00f3 a Russell Branyan para acortar distancias pero los hidroc\u00e1lidos volvieron a sonar en la segunda baja del bat de Carlos Orrant\u00eda sac\u00e1ndola del estadio con dos abordo para aumentar la ventaja de Aguascalientes 5-1.<\/p>\n<p>Eduardo Arredondo con l\u00ednea remolcadora de dos carreras en el cuarto episodio puso la pizarra 5-3 pero Carlos Orrant\u00eda y Jesse Castillo se combinaron para fabricar dos m\u00e1s en la parte baja de la cuarta, Russell Branyan hizo sonar su bat con panor\u00e1mico cuadrangular para acercar de nueva cuenta a Toros 7-4  en el electronico del Estadio Alberto Romo Ch\u00e1vez.<\/p>\n<p>Pero en la parte alta de la  sexta entrada con bateo oportuno Toros le dio la vuelta a la pizarra con rally de cuatro carreras que consisti\u00f3: Sencillo del emergente Rodrigo Aguirre, Arturo Rodriguez con el rancho ardiendo conect\u00f3 sencillo produciendo dos, Miguel Olivo recibi\u00f3 pasaporte con la casa llena  y Blake Gailen anot\u00f3 de \u201cCaballito\u201d la del despegue, pero en el mismo episodio Iv\u00e1n Bellazetin con elevado de sacrificio empat\u00f3 de nuevo la pizarra 8-8,  un s\u00f3lido ca\u00f1onazo solitario de Arturo Rodr\u00edguez en la parte alta del octavo rollo mando arriba a la novena tijuanense 9-8 y con la herm\u00e9tica serpentina de Dennys Reyes esto aunado a la fina defensiva de Toros bajaron la cortina en Aguascaliente, para que Tijuana se quedar\u00e1 con el juego.<br \/>\nOrlando Lara de Rielero y Alejandro Mart\u00ednez por Toros ambos abridores del segundo de la serie, salieron sin decisi\u00f3n.<\/p>\n<p>Dennys Reyes gan\u00f3  en relevo consiguiendo su primera victoria en el 2014 con Toros en labor de dos episodios  espaciando dos imparable, dos bases; 1 intencional y ponchando a dos. Ramberto Romo carg\u00f3 con el descalabro numero dos con Rieleros en una entrada de labor de 3 hits, 1 carrera y sin ponchar a nadie.<br \/>\nArturo Rodr\u00edguez se fue de 5-2 con tres impulsada, con cuadrangular, Eduardo Arredondo 4-2 con dos remolcadas y Russell Branyan conect\u00f3 jonr\u00f3n solitario y\u00e9ndose de 2-1 por Toros de Tijuana, mientras que por Rieleros de Aguascalientes Carlos Orrant\u00eda fue el mejor al bat al irse de 4-2 con cuatro producciones y vuelacercas, Willis Ota\u00f1ez  de 3-2 con cuadrangular y por \u00faltimo Carlos Rodr\u00edguez tambi\u00e9n repiti\u00f3 de imparable.<\/p>\n<p>Walter Silva (6-11) saltar\u00e1 a la loma del Estadio Alberto Romo Ch\u00e1vez para abrir por la novena de Jesus Sommers mientras que Mario Mendoza se reserv\u00f3 a su abridor para el tercero de la serie en Aguascalientes al filo de las 6:00 P.M. (4:00 P.M. hora de Tijuana).<\/p>\n<p>El juego lo pueden seguir por  Cadena 800 AM en radio o en internet por nuestras redes sociales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con jonr\u00f3n solitario de Arturo Rodr\u00edguez en la octava alta y herm\u00e9ticos lanzamientos del zurdo Dennys Reyes, Toros de Tijuana logra quedarse con la serie en la doble cartelera al ganar en extrainnings 9-8 ante Rieleros<\/p>\n","protected":false},"author":2,"featured_media":4659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4658"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4658\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4659"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}