{"id":4628,"date":"2014-07-31T00:00:00","date_gmt":"2014-07-31T07:00:00","guid":{"rendered":"http:\/\/10.255.248.8\/index.php\/2014\/07\/31\/se-acerca-dia-historico-para-toros-de-tijuana\/"},"modified":"2014-07-31T00:00:00","modified_gmt":"2014-07-31T07:00:00","slug":"se-acerca-dia-historico-para-toros-de-tijuana","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/se-acerca-dia-historico-para-toros-de-tijuana\/2014\/07\/","title":{"rendered":"Se acerca d\u00eda hist\u00f3rico para Toros de Tijuana"},"content":{"rendered":"<p><strong>Tijuana, B.C.- (torosdetijuana.com\/Gilberto Escobar) 31\/julio\/ 2014. &#8211; <\/strong>El pr\u00f3ximo domingo 3 de agosto del 2014 ser\u00e1 sin lugar a dudas, un parte aguas en la historia del beisbol mexicano. Dos equipos del circuito de mayor tradici\u00f3n del pa\u00eds irrumpir\u00e1n en un escenario de las Grandes Ligas para demostrar en otro suelo la calidad de pelota que se practica en territorio mexicano.<\/p>\n<p>Toros de Tijuana y Diablos Rojos del M\u00e9xico, deber\u00e1n sellar el tercer compromiso de su serie de rol regular, en el Petco Park de San Diego, California, que la casa de los Padres, conjunto de la Liga Nacional de MLB.<\/p>\n<p>Cabe resaltar que este partido nace de la buena relaci\u00f3n que existe entre el representante del grupo de due\u00f1os de Padres de San Diego, el Sr. Tom Sadlier con el presidente del consejo de administraci\u00f3n de Toros de Tijuana, el Sr. Alberto Uribe Maytorena. <\/p>\n<p>Ellos encabezaron la idea que se fue trabajando y madurando entre los dos equipos de trabajo de ambas organizaciones y al d\u00eda de hoy todo se encuentra listo para la realizaci\u00f3n de tan importante hecho para la Liga Mexicana de Beisbol, ya que ser\u00e1 apenas el segundo partido de rol regular, que se juegue en un parque de Grandes Ligas, hecho que sirve para difundir, promocionar y ofertar al beisbol de la Liga Mexicana.<\/p>\n<p>Los esfuerzos que se han realizado son muy importantes. No solo es asistir y jugar por parte de los equipos. Toros de Tijuana y Padres de San Diego han puesto empe\u00f1o en que todo salga a la perfecci\u00f3n para dejar un buen sabor de boca entre los aficionados mexicanos que viajar\u00e1n a Petco Park, as\u00ed como a los aficionados mexicanos y de otras nacionalidades que conocen la pelota de nuestro pa\u00eds pero que viven en el sur de California.<\/p>\n<p>La relaci\u00f3n entre Toros y Padres ha arrancado y no solo con este juego se mostrar\u00e1 el esfuerzo y el trabajo que al momento se han realizado. A la fecha ambas organizaciones tambi\u00e9n han trabajado en el sentido social, educativo, de nutrici\u00f3n y sobretodo en la salud infantil.<\/p>\n<p>Es por ello de la importancia para el beisbol mexicano la realizaci\u00f3n de este partido, ya que Toros de Tijuana abre una puerta muy importante dentro de la Liga Mexicana de Beisbol para expandir la calidad de nuestro juego. <\/p>\n<p>Adem\u00e1s las dos organizaciones han trabajado en hacer de ese domingo una fiesta para los asistentes. Destaca la presencia del mariachi, la banda sinaloense y toda la producci\u00f3n que est\u00e1 marcando diferencia en toda la LMB dentro del estadio Gasmart y que se trasladar\u00e1 a Petco Park para amenizar durante la jornada beisbolera, sin perder ese toque m\u00e1gico que brinda el estar en un parque del mejor beisbol del mundo.<\/p>\n<p>La jornada del pr\u00f3ximo domingo inicia a la 1:10 de la tarde con el encuentro de Grandes Liga entre Bravos de Atlanta visitando a Padres de San Diego y posteriormente la acci\u00f3n de la Liga Mexicana de Beisbol con toros de Tijuana recibiendo en Petco Park a Diablos Rojos del M\u00e9xico donde todos son bienvenidos.<\/p>\n<p>Informaci\u00f3n: Coordinaci\u00f3n de Medios Toros de Tijuana<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo domingo 3 de agosto del 2014 ser\u00e1 sin lugar a dudas, un parte aguas en la historia del beisbol mexicano. Dos equipos del circuito de mayor tradici\u00f3n del pa\u00eds irrumpir\u00e1n en un escenario de las Grandes Ligas<\/p>\n","protected":false},"author":2,"featured_media":4629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-4628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=4628"}],"version-history":[{"count":0,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/4628\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/4629"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=4628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=4628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=4628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}