{"id":16022,"date":"2026-01-02T19:01:01","date_gmt":"2026-01-03T02:01:01","guid":{"rendered":"https:\/\/torosdetijuana.com\/?p=16022"},"modified":"2026-01-15T18:08:49","modified_gmt":"2026-01-16T01:08:49","slug":"llega-gilberto-celestino-a-la-frontera","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/llega-gilberto-celestino-a-la-frontera\/2026\/01\/","title":{"rendered":"LLEGA GILBERTO CELESTINO A LA FRONTERA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El patrullero dominicano, Gilberto Celestino, con experiencia en Grandes Ligas reforzar\u00e1 las praderas de Toros de Tijuana<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TIJUANA, Baja California (<\/strong><a href=\"http:\/\/torosdetijuana.com\"><strong>TorosDeTijuana.Com<\/strong><\/a><strong>-David Soto) 2 de Enero del 2026.-<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La novena fronteriza contar\u00e1 en la temporada 2026 de Liga Mexicana de Beisbol (LMB) con la velocidad, contacto y destreza defensiva del jardinero dominicano Gilberto Celestino, con recorrido en el mejor b\u00e9isbol del mundo y en la pelota invernal, ser\u00e1 su primera experiencia en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nacido en Santo Domingo, Celestino firm\u00f3 como agente libre con los Astros de Houston en 2015, siendo considerado el s\u00e9ptimo mejor prospecto internacional por el portal oficial de MLB ese mismo a\u00f1o. Su talento lo llev\u00f3 a debutar en la Gran Carpa con los Mellizos de Minnesota, donde demostr\u00f3 sus cualidades en el outfield para cubrir terreno con rapidez y seguridad, adem\u00e1s de mostrar disciplina en el plato.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gilberto cuenta con recorrido en la Liga de B\u00e9isbol Profesional de la Rep\u00fablica Dominicana (LIDOM), el capitale\u00f1o ha jugado con los Gigantes del Cibao, \u00c1guilas Cibae\u00f1as y actualmente ha destacado como primer bat con los Toros del Este. En su pa\u00eds natal ha fortalecido su defensiva y lectura del juego, a la ofensiva bate\u00f3 .316, impuls\u00f3 17 carreras y se rob\u00f3 22 almohadillas durante la temporada regular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por si fuera poco, esta temporada Celestino se estableci\u00f3 como el segundo jugador en la historia de la LIDOM con una temporada de m\u00e1s de 50 imparables, 30 anotadas, 30 boletos y 20 bases robadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La combinaci\u00f3n de su experiencia en Grandes Ligas y su buen desempe\u00f1o en LIDOM, hacen de Gilberto Celestino un pelotero completo, capaz de marcar diferencia con su guante y madero. Su velocidad en las bases y el alcance en los jard\u00ednes lo perfilan como un elemento clave para el esquema de nuestro timonel, Roberto Kelly, aportando energ\u00eda y consistencia a la alineaci\u00f3n astada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FICHA T\u00c9CNICA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NOMBRE: <\/strong>Gilberto Celestino<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NACIMIENTO: <\/strong>13 de Febrero de 1999, Santo Domingo, Rep\u00fablica Dominicana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>POSICI\u00d3N: <\/strong>Jardinero<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LANZA: <\/strong>Zurdo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BATEA: <\/strong>Derecho<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EQUIPO MLB: <\/strong>Mellizos de Minnesota<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/torosdetijuana.com\/wp-content\/uploads\/2026\/01\/Celestino-1024x683.jpeg\" alt=\"\" class=\"wp-image-16024\" srcset=\"https:\/\/torosdetijuana.com\/wp-content\/uploads\/2026\/01\/Celestino-1024x683.jpeg 1024w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2026\/01\/Celestino-300x200.jpeg 300w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2026\/01\/Celestino-768x512.jpeg 768w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2026\/01\/Celestino-128x85.jpeg 128w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2026\/01\/Celestino-32x21.jpeg 32w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2026\/01\/Celestino-600x400.jpeg 600w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2026\/01\/Celestino.jpeg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\">Ser\u00e1 la primera experiencia de Gilberto Celestino en la pelota mexicana<\/mark><\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El patrullero dominicano, Gilberto Celestino, con experiencia en Grandes Ligas reforzar\u00e1 las praderas de Toros de Tijuana TIJUANA, Baja California (TorosDeTijuana.Com-David Soto) 2 de Enero del 2026.- La novena fronteriza contar\u00e1 en la temporada 2026 de Liga Mexicana de Beisbol (LMB) con la velocidad, contacto y destreza defensiva del jardinero dominicano Gilberto Celestino, con recorrido [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16023,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[549,552,522,182,553,427,371,550,415,551,538],"class_list":["post-16022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-gilberto-celestino","tag-jardin","tag-lidom","tag-lmb","tag-mellizos-de-minnesota","tag-mlb","tag-refuerzo","tag-republica-dominicana-2","tag-toros-de-tijuana","tag-toros-del-este","tag-twins"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/16022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=16022"}],"version-history":[{"count":2,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/16022\/revisions"}],"predecessor-version":[{"id":16026,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/16022\/revisions\/16026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/16023"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=16022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=16022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=16022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}