{"id":15885,"date":"2025-11-14T12:38:45","date_gmt":"2025-11-14T19:38:45","guid":{"rendered":"https:\/\/torosdetijuana.com\/?p=15885"},"modified":"2025-11-14T12:42:08","modified_gmt":"2025-11-14T19:42:08","slug":"el-arte-de-controlar-el-juego-mental","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/el-arte-de-controlar-el-juego-mental\/2025\/11\/","title":{"rendered":"EL ARTE DE CONTROLAR EL JUEGO MENTAL"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La preparaci\u00f3n y el temple de dominar el mont\u00edculo, la fortaleza que David Reyes ha encontrado en su camino por la lomita<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TIJUANA, Baja California (<\/strong><a href=\"http:\/\/torosdetijuana.com\"><strong>TorosDeTijuana.Com<\/strong><\/a><strong>-David Soto) 14 de Noviembre del 2025.-<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el paso de los innings y grandes salidas, \u201cEl Rey David\u201d se ha consolidado como uno de los serpentineros de mayor calidad dentro del b\u00e9isbol mexicano. Las actuaciones herm\u00e9ticas y la resiliencia del mochiteco han llevado a Reyes a dejar grandes n\u00fameros, donde los 100 triunfos est\u00e1n a la vuelta de la esquina en la venidera campa\u00f1a veraniega.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras una buena temporada en la Liga Mexicana de Beisbol (LMB) con Toros de Tijuana, las tres victorias que Reyes consigui\u00f3 con los bureles en el cierre de temporada lo ponen a ley de seis triunfos y 23 chocolates m\u00e1s de llegar al centenar de victorias y 900 ponches en su carrera de LMB. Cifras que no cualquier lanzador registra en su carrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, David se encuentra lanzando con los \u00c1guilas de Mexicali en la Liga Mexicana del Pac\u00edfico (LMP), el sinaloense sabe que el enfoque en la lomita y no confiarse son claves para evitar da\u00f1o ante el alto nivel de competencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos primeros seis de la alineaci\u00f3n son los de m\u00e1s cuidado, uno se enfoca en hacer los menos errores , porque si le das importancia es donde el bateador d\u00e9bil te hace da\u00f1o. Si caes en el conformismo de que vas a descansar un poco porque vienen siete, ocho y nueve del orden al bat, es donde m\u00e1s da\u00f1o te hacen. La parte alta del line up es donde hay que seguir con la misma t\u00f3nica, atacando y mantenerte enfocado en tus pitcheos al cien por ciento\u201d, aclar\u00f3 Reyes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son 14 las temporadas que respaldan el trabajo de David Reyes en la LMP, su 3.34 de efectividad de carreras limpias (ERA) de por vida en la pelota invernal, as\u00ed como los 610 ponches que acumula en su trabajo monticular a la fecha, son muestra de su calidad y representan momentos de orgullo familiar y fortaleza mental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDisfruto lanzando, no me enfoco en que soy el n\u00famero uno o dos de los mejores pitchers de la temporada actual. Y resulta bonito, representar eso de parte m\u00eda, de parte de mi familia, de que ellos est\u00e9n orgullosos del apellido que traigo atr\u00e1s y del trabajo que realizo. Estoy contento hasta el momento, no lo tomo de presi\u00f3n ni nada, solo disfruto lo poco y lo bueno, siempre dando lo mejor\u201d, detall\u00f3 el lanzador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La experiencia y aprendizaje que dejan los a\u00f1os no tiene precio, la veteran\u00eda para Reyes es un factor del que hay que aprovechar y seguir aprendiendo en el camino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSacarle el mayor provecho posible a mi experiencia, el veterano sabe c\u00f3mo lidiar con las diferentes situaciones, son muchos a\u00f1os que uno va aprendiendo y va mejorando en todos los aspectos, tanto f\u00edsico como mental, la parte mental es la m\u00e1s fuerte que debemos de tener\u201d, finaliz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EL AMBIENTE Y CALIDEZ DEL CLUBHOUSE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl ambiente en Tijuana es bonito, se disfruta mucho el juego cuando est\u00e1s en el terreno y cuando no, se goza en general. La vibra es buena y el compa\u00f1erismo ni se diga, desde que llegu\u00e9 me arroparon como si fuera uno m\u00e1s de ellos y estoy contento de vivir esos buenos momentos ah\u00ed y esperemos que sean m\u00e1s\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FICHA T\u00c9CNICA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nombre: David Antonio Reyes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fecha de nacimiento: 12 Abril 1990<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lanza: Derecho<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Temporadas LMP: 14 (60 G &#8211; 42 P, 3.34 ERA, 610 K)&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Temporadas LMB: 15 (94 G &#8211; 65 P, 4.65 ERA, 877 K)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Equipos en LMB: Oaxaca, M\u00e9xico, Veracruz y Tijuana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Equipos en LMP: Obreg\u00f3n y Mexicali<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/torosdetijuana.com\/wp-content\/uploads\/2025\/07\/DPL3356-1024x683.jpg\" alt=\"David Reyes\" class=\"wp-image-14967\" srcset=\"https:\/\/torosdetijuana.com\/wp-content\/uploads\/2025\/07\/DPL3356-1024x683.jpg 1024w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2025\/07\/DPL3356-300x200.jpg 300w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2025\/07\/DPL3356-768x512.jpg 768w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2025\/07\/DPL3356-1536x1024.jpg 1536w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2025\/07\/DPL3356-2048x1365.jpg 2048w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2025\/07\/DPL3356-128x85.jpg 128w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2025\/07\/DPL3356-32x21.jpg 32w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2025\/07\/DPL3356-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La preparaci\u00f3n y el temple de dominar el mont\u00edculo, la fortaleza que David Reyes ha encontrado en su camino por la lomita.<\/p>\n","protected":false},"author":2,"featured_media":15886,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[282,414,442,526,522,182,518,427,489,283,436,488,390,445,183,210,486,490,532,272,188,267],"class_list":["post-15885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-aderlin","tag-david-reyes","tag-dominicana","tag-firma","tag-lidom","tag-lmb","tag-lmp","tag-mlb","tag-mobil-park","tag-monclova","tag-oscar-robles","tag-playoff","tag-playoffs","tag-postemporada","tag-presentacion","tag-previa","tag-rangel-ravelo","tag-republica","tag-rising-stars","tag-rodriguez","tag-tijuana","tag-toros"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/15885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=15885"}],"version-history":[{"count":2,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/15885\/revisions"}],"predecessor-version":[{"id":15891,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/15885\/revisions\/15891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/15886"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=15885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=15885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=15885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}