{"id":14068,"date":"2025-05-12T00:30:59","date_gmt":"2025-05-12T07:30:59","guid":{"rendered":"https:\/\/torosdetijuana.com\/?p=14068"},"modified":"2025-08-16T23:16:24","modified_gmt":"2025-08-17T06:16:24","slug":"ganan-y-amarran-serie","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/ganan-y-amarran-serie\/2025\/05\/","title":{"rendered":"GANAN Y AMARRAN SERIE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Toros de Tijuana venci\u00f3 10-2 a Algodoneros Uni\u00f3n Laguna para amarrar la serie en el Estadio Revoluci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 11 de mayo del 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Danny Ortiz son\u00f3 cuadrangular con bases llenas y Raudy Read agreg\u00f3 jonr\u00f3n solitario en respaldo a la joya monticular de Caleb Baragar en la victoria de Toros de Tijuana por 10-2 sobre Algodoneros Uni\u00f3n Laguna en el Estadio Revoluci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Fue el primer \u201cgrandslam\u201d de la campa\u00f1a para el conjunto fronterizo que amarr\u00f3 la serie y engros\u00f3 su r\u00e9cord a 12-8 en la segunda posici\u00f3n de la Zona Norte, a dos juegos y medio por debajo del l\u00edder Sultanes de Monterrey.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Toros de Tijuana anot\u00f3 a cuenta gotas para adelantarse con las primeras dos carreras del juego. Raudy Read rompi\u00f3 el hielo en la cuarta entrada con cuadrangular solitario por el jard\u00edn izquierdo y en la siguiente ronda Blake Rutherford son\u00f3 doblete contra la barda de ladrillo del prado derecho y anot\u00f3 el 2-0 con globo de sacrificio de Tom\u00e1s Telis al central.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Una rayita m\u00e1s para los bureles se anot\u00f3 en el sexto tramo en los pies de Jos\u00e9 Guadalupe Ch\u00e1vez, quien bate\u00f3 doblete y lleg\u00f3 a la registradora al aprovechar un error de Jonathan Schopp a batazo de Blake Rutherford.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La ventaja de los dirigidos por \u00d3scar Robles se redujo al m\u00ednimo en un parpadeo cuando los anfitriones anotaron con doblete productor de Albert Lara y sencillo impulsor de Jos\u00e9 Godoy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los bureles abrieron la compuerta en la sexta ronda y fue con el primer \u201cgrandslam\u201d en la temporada. Danny Ortiz se encontr\u00f3 con los senderos congestionados y aprovech\u00f3 para disparar jonr\u00f3n qu\u00e9 carg\u00f3 con Isaac Rodr\u00edguez, Hern\u00e1n P\u00e9rez y Raudy Read para el categ\u00f3rico 7-2 en el pizarr\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Fue la ocasi\u00f3n 36 que Toros de Tijuana se lleva la barda con bases llenas en su historial y la tercera contra el conjunto lagunero.<br>En la pizarra todav\u00eda faltaban las tres carreras de la octava ronda y se acreditaron a la parte alta de la tirilla. Edson Garc\u00eda timbr\u00f3 con sencillo de Hern\u00e1n P\u00e9rez, Gabriel Noriega complet\u00f3 su vuelta con \u201cwild pitch\u201d de Yoan L\u00f3pez e Isaac Rodr\u00edguez tambi\u00e9n cruz\u00f3 la registradora cuando Junior Lake respondi\u00f3 con imparable al jard\u00edn izquierdo para el 10-2 final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">138 PITCHERS GANADORES<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Caleb Baragar abri\u00f3 el duelo y se llev\u00f3 la victoria en cinco rondas sin carrera, un hit, dos bases por bolas, cuatro ponches en una econ\u00f3mica exhibici\u00f3n de 59 lanzamientos, 33 de ellos por la zona buena. Fue su primer triunfo de la campa\u00f1a y tambi\u00e9n de su carrera con la embestida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Con el zurdo de Michigan, ahora son 138 diferentes lanzadores los que han ganado al menos un juego con la casaca fronteriza. El primero fue Jos\u00e9 N\u00fa\u00f1ez el 18 de marzo del 2004.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Preservaron la victoria David Guti\u00e9rrez para dos carreras en un tercio, Jake Fishman en blanco dos tercios, Ralph Garza Jr. sin problemas la s\u00e9ptima tanda, Teddy Stankiewicz debut\u00f3 en la octava ronda sin contratiempos y Jos\u00e9 \u00c1lvarez complet\u00f3 el tr\u00e1mite en el noveno rollo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Perdi\u00f3 Miguel V\u00e1zquez en cuatro cap\u00edtulos de par de carreras, cuatro imparables, un pasaporte y cinco chocolates. Lo relevaron Jes\u00fas Reyes, Matt Fodter, Fernando Abad cuatro carreras en un episodio, Yoan L\u00f3pez dos anotaciones en un tercio, Matt Tenuta y Thomas McIlraith.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CIERRA SERIE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En \u201cLunes Beisbolero\u201d los Toros de Tijuana cerrar\u00e1n la serie de visita a Algodoneros Uni\u00f3n Laguna en el Estadio Revoluci\u00f3n. El tercer duelo iniciar\u00e1 a las 18:30 (Horario de Tijuana)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los lanzadores anunciados son Jorge P\u00e9rez (2-1; 2.25) por la novena bajacaliforniana y Aldo Montes (3-0; 1.17) por la escuadra que dirige Jos\u00e9 Molina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">PIZARRA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>EQUIPO 123 456 789 C H E<br>Tijuana 000 111 430 10 12 0<br>Laguna 000 002 000 2 4 1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Pitcher ganador: Caleb Baragar (0-3)<br>Pitcher derrotado: Miguel V\u00e1zquez (1-0)<br>Cuadrangulares: (TIJ) Raudy Read (3) y Danny Ortiz (3)<br>Estadio: Revoluci\u00f3n<br>Asistencia: 6 mil 584 aficionados<br>Duraci\u00f3n: 2 horas y 54 minutos<br>Ampayers: (H) Rodolfo Pastrana, (1B) Alfredo Soto, (2B) Jos\u00e9 Tirado y (3B) Daniel Toledo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toros de Tijuana venci\u00f3 10-2 a Algodoneros Uni\u00f3n Laguna para amarrar la serie en el Estadio Revoluci\u00f3n TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 11 de mayo del 2025 Danny Ortiz son\u00f3 cuadrangular con bases llenas y Raudy Read agreg\u00f3 jonr\u00f3n solitario en respaldo a la joya monticular de Caleb Baragar en la victoria de Toros de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14067,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-14068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/14068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=14068"}],"version-history":[{"count":2,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/14068\/revisions"}],"predecessor-version":[{"id":15311,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/14068\/revisions\/15311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/14067"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=14068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=14068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=14068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}