{"id":14040,"date":"2025-05-07T22:24:03","date_gmt":"2025-05-08T05:24:03","guid":{"rendered":"https:\/\/torosdetijuana.com\/?p=14040"},"modified":"2025-08-19T11:31:16","modified_gmt":"2025-08-19T18:31:16","slug":"remontan-y-ganan-serie","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/remontan-y-ganan-serie\/2025\/05\/","title":{"rendered":"REMONTAN Y GANAN SERIE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Toros de Tijuana se quit\u00f3 una desventaja de cinco carreras para ligar su sexta victoria al derrotar 10-9 a Saraperos de Saltillo en el Estadio Francisco I. Madero<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 7 de mayo del 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Hern\u00e1n P\u00e9rez y Danny Ortiz se volaron la barda y Toros de Tijuana vino de atr\u00e1s para vencer 10-9 a Saraperos de Saltillo y ganar la serie en el Estadio Francisco I. Madero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El conjunto fronterizo remont\u00f3 desventajas de cinco y cuatro carreras para ligar su sexta victoria y fortalecer su r\u00e9cord a 10-7 en la segunda posici\u00f3n de la Zona Norte, a dos juegos por debajo del l\u00edder Sultanes de Monterrey.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los anfitriones se alborotaron en su turno del segundo cap\u00edtulo y emboscaron a Julio Teher\u00e1n para adelantarse con ataque de cinco carreras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Alex Mej\u00eda y Carlos Mart\u00ednez remolcaron las primeras tres con sendos sencillos y J. P. Mart\u00ednez empuj\u00f3 dos con doblete para completar el p\u00f3ker de carreras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La embestida respondi\u00f3 r\u00e1pido con cuatro anotaciones al abrirse el tercer episodio. Tom\u00e1s Telis anot\u00f3 en un rodado de Jos\u00e9 Guadalupe Ch\u00e1vez que se combin\u00f3 con un error del lanzador Zach Mort, luego Isaac Rodr\u00edguez elev\u00f3 al central para que marcara Gabriel Noriega de \u201cpisa y corre\u201d y Raudy Read propuls\u00f3 a Jos\u00e9 Guadalupe Ch\u00e1vez y Junior Lake con imparable al izquierdo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Saraperos volvi\u00f3 a la carga al cerrar la quinta ronda con doblete de Missael Rivera que empuj\u00f3 a J. P. Mart\u00ednez y Brandon Villarreal. Adem\u00e1s, el propio Rivera complet\u00f3 la vuelta al cuadro con hit de Jos\u00e9 Peraza para el 8-4 parcial en los cartones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los dirigidos por \u00d3scar Robles se acercaron con dos rayitas en el sexto acto con doblete impulsor de Danny Ortiz, quien m\u00e1s tarde cruz\u00f3 por el pent\u00e1gono con hit de Telis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El empate fronterizo cay\u00f3 en la s\u00e9ptima entrada con cuadrangular de Hern\u00e1n P\u00e9rez con Isaac Rodr\u00edguez en el tr\u00e1fico y se despegaron en el octavo tramo con otra tabla, en esta ocasi\u00f3n cortes\u00eda de Danny Ortiz para completar la remontada en 9-8.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La carrera de la aseguranza se apunt\u00f3 en el noveno acto con sencillo de Jos\u00e9 Guadalupe Ch\u00e1vez, quien dej\u00f3 su lugar al corredor emergente Edson Garc\u00eda y enseguida se ejecut\u00f3 toque de bola a cargo de Isaac Rodr\u00edguez para que llegara el sencillo impulsor de Hern\u00e1n P\u00e9rez que complet\u00f3 la decena en la parte alta de la tirilla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los locales hicieron su \u00faltimo intento por conseguir la paridad en la novena campanada cuando timbraron con sencillo productor de Brandon Villarreal, pero fue todo lo que pudieron subir a la pizarra y se quedaron cortos por segunda noche consecutiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los astados ganaron serie en Saltillo por primera ocasi\u00f3n desde el 2019. El jueves buscar\u00e1n su primera barrida en el domicilio del \u201cSarape\u201d desde la segunda campa\u00f1a del 2018.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EN LA LOMITA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Julio Teher\u00e1n abri\u00f3 por Toros de Tijuana y se fue sin decisi\u00f3n luego de cuatro entradas y cuatro bateadores del quinto tramo.<br>Fue responsable de ocho carreras, nueve hits, una base por bolas y dos ponches. Su efectividad se elev\u00f3 a 8.10 en cuatro aperturas del 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En su auxilio pasaron la bola Roel Ram\u00edrez con una ronda en blanco, Jake Fishman cruz\u00f3 la sexta entrada sin mancharse, el ganador Jos\u00e9 \u00c1lvarez argolla en la s\u00e9ptima, Ralph Garza en blanco la octava, David Guti\u00e9rrez dos tercios de una carrera y Luis M\u00e1rquez el \u00faltimo out para su segundo rescate en d\u00edas consecutivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Por Saraperos el diestro Zach Mort aspiraba al triunfo al dejar el juego ganado tras cumplir con las cinco rondas de rigor en cuatro carreras, tres de ellas sucias, cinco imparables, un pasaporte y cuatro chocolates, sin embargo, el bullpen lo sac\u00f3 de la decisi\u00f3n.<br>Se mantuvo sin victorias en cuatro aperturas y redujo a 4.71 su porcentaje de carreras limpias admitidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Pedro Rodr\u00edguez fue el primer relevo y lo tocaron con dos carreras en el sexto acto, Mario Meza perdi\u00f3 la ventaja al aceptar dos anotaciones en la entrada de la suerte, el derrotado Danis Correa con una rayita en el octavo rollo y termin\u00f3 Ryan Mesinger con otra carrera en su cuenta<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CIERRA SERIE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Toros de Tijuana buscar\u00e1 completar la limpia el jueves cuando se vuelva a topar con Saraperos de Saltillo en el tercer choque pactado para las 18:30 (horario de Tijuana) en el Estadio Francisco I. Madero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los lanzadores probables son Matt Dermody (1-0; 1.69) por la escuadra fronteriza, mientras que Enrique Che\u201d Reyes le dar\u00e1 la pelota a Kurt Heyer (0-0; 1.69).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">PIZARRA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>EQUIPO 123 456 789 C H E<br>Tijuana 004 002 211 10 12 0<br>Saltillo 050 030 001 9 13 1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Pitcher ganador: Jos\u00e9 \u00c1lvarez (1-0)<br>Pitcher derrotado: Danis Correa (1-2)<br>Salvamento: Luis M\u00e1rquez (2)<br>Cuadrangulares: (TIJ) Hern\u00e1n P\u00e9rez (2) y Danny Ortiz (2)<br>Estadio: Francisco I. Madero<br>Asistencia: 3 mil 788 aficionados<br>Duraci\u00f3n: 3 horas y 22 minutos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toros de Tijuana se quit\u00f3 una desventaja de cinco carreras para ligar su sexta victoria al derrotar 10-9 a Saraperos de Saltillo en el Estadio Francisco I. Madero TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 7 de mayo del 2025 Hern\u00e1n P\u00e9rez y Danny Ortiz se volaron la barda y Toros de Tijuana vino de atr\u00e1s para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14039,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-14040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/14040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=14040"}],"version-history":[{"count":2,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/14040\/revisions"}],"predecessor-version":[{"id":15329,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/14040\/revisions\/15329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/14039"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=14040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=14040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=14040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}