{"id":13916,"date":"2025-04-27T22:13:19","date_gmt":"2025-04-28T05:13:19","guid":{"rendered":"https:\/\/torosdetijuana.com\/?p=13916"},"modified":"2025-08-19T12:32:34","modified_gmt":"2025-08-19T19:32:34","slug":"cede-toros-serie-completa","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/cede-toros-serie-completa\/2025\/04\/","title":{"rendered":"CEDE TOROS SERIE COMPLETA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Toros de Tijuana no tuvo poder de reacci\u00f3n y perdi\u00f3 9-4 ante Tecolotes de los Dos Laredos en el Parque La Junta<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 27 de abril del 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Toros de Tijuana cay\u00f3 9-4 ante Tecolotes de los Dos Laredos y dej\u00f3 la serie completa en el duelo dominical que se desarroll\u00f3 en el Parque La Junta de Nuevo Laredo Tamaulipas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Con el rev\u00e9s el conjunto fronterizo vio reducirse su r\u00e9cord a 3-6 en la s\u00e9ptima posici\u00f3n de la Zona Norte en la temporada 2025 de Liga Mexicana de Beisbol (LMB).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los anfitriones no esperaron mucho para ponerse en acci\u00f3n y atacaron con racimo de cinco carreras que marc\u00f3 el camino del encuentro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Danry V\u00e1squez son\u00f3 cuadrangular para llevarse en la ola a Al\u00ed Castillo y luego Jes\u00fas Mart\u00ednez bate\u00f3 doblete con bases llenas para empujar a Harold Ram\u00edrez, Yadiel Hern\u00e1ndez y Francisco Arcia para un carrusel que dibuj\u00f3 el 5-0 en la pizarra del parque de la calle Venustiano Carranza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Toros de Tijuana se inscribi\u00f3 en el marcador al abrirse el quinto tramo y lo hicieron con dos carreras que fabricaron con sencillo de Hern\u00e1n P\u00e9rez que le dio impulso a Rudy Martin Jr. y Jack Mayfield para el 5-2 parcial.<br>La reacci\u00f3n burel se qued\u00f3 corta y los anfitriones se encargaron de dar el golpe sobre la mesa con tres rayitas m\u00e1s en el quinto cap\u00edtulo para despegarse de una vez por todas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Yadiel Hern\u00e1ndez con sencillo, Francisco Arcia con doblete y Jos\u00e9 Mart\u00ednez con hit al izquierdo, empujaron la tercia de carreras que alteraron el electr\u00f3nico a 8-2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Una m\u00e1s para los dirigidos por F\u00e9lix Ferm\u00edn en el cierre del sexto episodio con la cuarta tabla de Yadiel Hern\u00e1ndez en la campa\u00f1a.<br>Los astados descontaron en la s\u00e9ptima cuando Raudy Read y Junior Lake sonaron dobletes para la tercera anotaci\u00f3n en la parte alta de la tirilla y agregaron una m\u00e1s en el \u00faltimo suspiro con incogible productor al central de Lake que marc\u00f3 los n\u00fameros finales de la velada en 9-4.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los mejores bats de la embestida fueron Rudy Martin Jr. con tres hits y Blake Rutherford con un par de batazos a tierra de nadie.<br>Fue la segunda barrida que sufre Toros de Tijuana de visita en la frontera Noreste. La anterior se registr\u00f3 del 25 al 27 de julio del 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>S\u00f3lo en la campa\u00f1a 2016 los bureles iniciaron la temporada con tres victorias y seis derrotas. En aquel a\u00f1o fueron campeones de la Zona Norte y disputaron la Serie del Rey.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCANELO\u201d SE ESTRENA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Luis Javier Amador conect\u00f3 el primer hit de su carrera como profesional en Liga Mexicana de Beisbol (LMB).<br>El de Cadua\u00f1o. Baja California Sur, dispar\u00f3 sencillo al jard\u00edn central a un lanzamiento del abridor ex ligamayorista Daniel Mengden en la segunda entrada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El receptor debut\u00f3 en 2024 y se fue en blanco en cuatro turnos. El hit lleg\u00f3 en su tercera oportunidad con el madero de la presente campa\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DEBUTA CASTA\u00d1EDA JR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Rafael Casta\u00f1eda Jr. vio su primera luz en Liga Mexicana de Beisbol (LMB). El hijo del \u201cChivig\u00f3n\u201d lanz\u00f3 la novena entrada en orden para presentarse en el circuito en el que su padre fue estrella por muchos a\u00f1os.<br>El nacido en Ciudad de M\u00e9xico domin\u00f3 a Al\u00ed Castillo, Danry V\u00e1squez y Harold Ram\u00edrez para la primera entrada en su historial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EN LA LOMITA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Matt Dermody fue el abridor de Toros de Tijuana y no pudo escapar de la primera entrada.<br>El zurdo de Iowa fue castigado con cinco carreras y cuatro hits en apenas dos tercios. Ponch\u00f3 a uno y regal\u00f3 dos bases por bolas.<br>Fue su segunda derrota en el mismo n\u00famero de aperturas en la naciente temporada 2025 de LMB.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Relevaron desde muy temprano Jake Fishman para una entrada y un tercio, Daniel Zamora argolla en la cuarta tanda, Parker Dunshee, Luis M\u00e1rquez, Bryan Rodr\u00edguez, Roel Ram\u00edrez y Rafael Casta\u00f1eda en orden la octava.<br>El ganador en el mont\u00edculo fue Daniel Mengden en cinco tandas de dos carreras y cinco hits, con cuatro pasaportes y cinco chocolates. Le ayudaron Adolfo Ram\u00edrez, Beau Burrows, Andrew V\u00e1squez y<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VIAJAN A JALISCO<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Toros de Tijuana se mantendr\u00e1 en la carretera para completar su primera gira de la temporada. El lunes viajar\u00e1n a Guadalajara para abrir serie el martes contra Charros de Jalisco en el Estadio Panamericano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Para los duelos en el inmueble que se encuentra en el municipio de Zapopan los astados contar\u00e1n en la lomita con Phillips Valdez, Jorge P\u00e9rez y Julio Teher\u00e1n en ese orden, mientras que los anfitriones se defender\u00e1n con los brazos de Jeremy Rhoades, Eli\u00e1n Leyva y Luis Pay\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La novena tijuanense regresar\u00e1 a casa para jugar contra Dorados de Chihuahua de viernes a domingo en el Mobil Park.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">PIZARRA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>EQUIPO 123 456 789 C H E<br>Tijuana 000 020 100 4 10 0<br>Dos Laredos 500 031 00x 9 10 3<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Pitcher ganador: Daniel Mengden (1-0)<br>Pitcher derrotado: Matt Dermody (0-2)<br>Cuadrangulares: (LAR) Danry V\u00e1squez (1) y Yadiel Hern\u00e1ndez (4)<br>Estadio: La Junta<br>Asistencia: 3 mil 881 aficionados<br>Duraci\u00f3n: 3 horas y 12 minutos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toros de Tijuana no tuvo poder de reacci\u00f3n y perdi\u00f3 9-4 ante Tecolotes de los Dos Laredos en el Parque La Junta TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 27 de abril del 2025 Toros de Tijuana cay\u00f3 9-4 ante Tecolotes de los Dos Laredos y dej\u00f3 la serie completa en el duelo dominical que se desarroll\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13915,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-13916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=13916"}],"version-history":[{"count":2,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13916\/revisions"}],"predecessor-version":[{"id":15341,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13916\/revisions\/15341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/13915"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=13916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=13916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=13916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}