{"id":13890,"date":"2025-04-23T22:19:29","date_gmt":"2025-04-24T05:19:29","guid":{"rendered":"https:\/\/torosdetijuana.com\/?p=13890"},"modified":"2025-08-19T12:38:55","modified_gmt":"2025-08-19T19:38:55","slug":"cierre-triunfal","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/cierre-triunfal\/2025\/04\/","title":{"rendered":"CIERRE TRIUNFAL"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Toros de Tijuana super\u00f3 7-4 a Sultanes de Monterrey para evitar la limpia en el Mobil Park<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 23 de abril del 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Hern\u00e1n P\u00e9rez son\u00f3 cuadrangular y empuj\u00f3 par de carreras en respaldo a la educada exhibici\u00f3n monticular de Jorge P\u00e9rez, en ruta a la victoria de Toros de Tijuana por 7-4 sobre Sultanes de Monterrey en el cierre de serie en Mobil Park.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Con el triunfo, el conjunto fronterizo evit\u00f3 la limpia y mejor\u00f3 su marca a 3-3 para ascender a la cuarta posici\u00f3n de la Zona Norte.<br>Toros de Tijuana rasg\u00f3 el celof\u00e1n desde la parte baja de la misma primera entrada para tomar una ventaja que nunca perdieron. Hern\u00e1n P\u00e9rez produjo su primera carrera de la noche con sencillo que empuj\u00f3 a Rudy Martin y m\u00e1s tarde anot\u00f3 Raudy Read con \u201cwild pitch\u201d del lanzador Stephen Tarpley para el 2-0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los regios redujeron su d\u00e9ficit a la mitad al abrirse la tercera ronda con jonr\u00f3n solitario de Jos\u00e9 Cardona, pero los bureles respondieron con la misma divisa por conducto de Hern\u00e1n P\u00e9rez, quien super\u00f3 el per\u00edmetro del jard\u00edn central para alterar el electr\u00f3nico a 3-1.<br>Fue el primer cuadrangular del venezolano en la temporada y el segundo en su carrera con la novena tijuanense. El primero lo peg\u00f3 en la serie inaugural de la campa\u00f1a 2022 contra Diablos Rojos del M\u00e9xico.<br>Los Toros mantuvieron la llave abierta y \u201cpusieron pies en polvorosa\u201d con pesado ataque de cuatro carreras en el fondo del cuarto acto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Al\u00ed Sol\u00eds le dio forma a la figura del \u201cpisa y corre\u201d con globo al izquierdo que remolc\u00f3 a Gabriel Noriega, luego Rudy Martin conect\u00f3 el primer triple de la temporada burel y fue bueno para remolcar a Phillip Evans, enseguida Isaac Rodr\u00edguez empalm\u00f3 sencillo productor y Raudy Read tambi\u00e9n empuj\u00f3 carrera con rodado a las paradas cortas que le dio forma al categ\u00f3rico 7-1 en los cartones con cuatro entradas en los libros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Rodr\u00edguez lleg\u00f3 a 278 carreras producidas y volvi\u00f3 a empatar a Junior Lake en el liderato hist\u00f3rico de la franquicia.<br>La escuadra que dirige Roberto Kelly descont\u00f3 en la entrada de la suerte con otro imparable de Jos\u00e9 Cardona., el \u00fanico bateador que se le indigest\u00f3 al abridor tijuanense Jorge P\u00e9rez. \u201cMeteoro\u201d conect\u00f3 sencillo para empujar a Ramiro Pe\u00f1a con la segunda carrera de la visita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>N\u00fameros finales se decretaron en el octavo acto.<br>Ramiro Pe\u00f1a elev\u00f3 al central y Donovan Casey marc\u00f3 el 7-3 de \u201cpisa y corre\u201d. Enseguida apareci\u00f3 Esteban Quiroz con su primer imparable de la campa\u00f1a para remitir a Roberto Valenzuela al pent\u00e1gono.<br>Los mejores bats en el bando ganador fueron los de Hern\u00e1n P\u00e9rez de 3-2 con tabla y dos remolques, Rudy Martin Jr. de 4-2 con triple, doble, carrera empujada y dos anotadas y Gabriel Noriega con tres inatrapables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>A la historia entre Toros y Sultanes en la temporada regular 2025 a\u00fan le faltan varios cap\u00edtulos. Seis para ser exactos.<br>Se volver\u00e1n a cruzar del 24 al 26 de mayo cuando los \u201cfantasmas grises\u201d regresen al Mobil Park y del 11 al 13 de julio en el Estadio Walmart.<br>La \u00faltima ocasi\u00f3n que Sultanes de Monterrey gan\u00f3 serie completa a Toros de Tijuana se remonta a mayo del 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EN LA LOMITA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Jorge P\u00e9rez lig\u00f3 salidas de calidad. En esta ocasi\u00f3n la alcanz\u00f3 para su primer triunfo de la campa\u00f1a.<br>El diestro se extendi\u00f3 a seis entradas y un tercio de dos carreras y siete hits con par de ponches sin regalar pasaportes. Fue la duod\u00e9cima victoria en su carrera con Toros de Tijuana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En relevo Daniel Zamora sofoc\u00f3 la rebeli\u00f3n de la s\u00e9ptima tanda, Parker Dunshee un tercio de la octava ronda en su debut con dos carreras, David Guti\u00e9rrez un tercio y Jimmy Cordero con el rescate de cuatro outs. Fue el segundo salvamento en la campa\u00f1a para el dominicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La derrota fue al r\u00e9cord de Stephen Tarpley al aceptar todo el da\u00f1o con nueve hits, dos pasaportes y tres chocolates. Fue el tercer intento fallido de Tarpley contra Toros de Tijuana.<br>Le ayudaron Erick Rodr\u00edguez, Juan G\u00e1mez y Ger\u00f3nimo Franzua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">PRIMERA GIRA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Toros de Tijuana emprender\u00e1 su primera gira de la temporada cuando visiten a Tecolotes de los Dos Laredos de viernes a domingo.<br>Los primeros dos juegos tendr\u00e1n como escenario el Estadio Uni-Trade y para el domingo las acciones se trasladar\u00e1n al Parque La Junta de Nuevo Laredo. Los ampayers llamar\u00e1n a juego a las 17:30 en los tres desaf\u00edos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El historial de Toros y Tecolotes tiene 55 p\u00e1ginas. Los bureles han ganado 23 juegos y los binacionales 22.<br>Los tamaulipecos han ganado las cinco m\u00e1s recientes series disputadas, adem\u00e1s, los emplumados han dominado en su guarida en las \u00faltimas cuatro series entre ambos equipos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">PIZARRA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>EQUIPO 123 456 789 C H E<br>Monterrey 001 000 120 4 10 1<br>Tijuana 201 400 00x 7 11 0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Pitcher ganador: Jorge P\u00e9rez (1-0)<br>Pitcher derrotado: Stephen Tarpley (0-1)<br>Cuadrangulares: Hern\u00e1n P\u00e9rez (1)<br>Salvamento: Jimmy Cordero (2)<br>Estadio: Mobil Park<br>Asistencia: 5 mil 352 aficionados<br>Duraci\u00f3n: 2 horas y 54 minutos<br>Ampayers: (H) Roberto LaMadrid, (1B) Carlos Le\u00f3n, (2B) Alan Cruz y (3B) Emmanuel Peregrina Aguirre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toros de Tijuana super\u00f3 7-4 a Sultanes de Monterrey para evitar la limpia en el Mobil Park TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 23 de abril del 2025 Hern\u00e1n P\u00e9rez son\u00f3 cuadrangular y empuj\u00f3 par de carreras en respaldo a la educada exhibici\u00f3n monticular de Jorge P\u00e9rez, en ruta a la victoria de Toros de Tijuana [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-13890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=13890"}],"version-history":[{"count":2,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13890\/revisions"}],"predecessor-version":[{"id":15346,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13890\/revisions\/15346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/13891"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=13890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=13890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=13890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}