{"id":13782,"date":"2025-04-04T12:28:33","date_gmt":"2025-04-04T19:28:33","guid":{"rendered":"https:\/\/torosdetijuana.com\/?p=13782"},"modified":"2025-08-19T12:53:30","modified_gmt":"2025-08-19T19:53:30","slug":"somos-puros-ganadores","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/somos-puros-ganadores\/2025\/04\/","title":{"rendered":"\u201cSOMOS PUROS GANADORES\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con \u201cGuante de Oro\u201d en la mano, Isaac Rodr\u00edguez apunta su mira a la Serie del Rey del 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 4 de abril del 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Isaac Rodr\u00edguez no tiene ninguna duda, en Toros de Tijuana hay puros ganadores. El estelar segunda base acelera su puesta a punto y asegura que la personalidad es lo m\u00e1s importante en el grupo de m\u00e1s de cuarenta jugadores que trabajan sin descanso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Reci\u00e9n designado -por tercer a\u00f1o consecutivo- como ganador del \u201cGuante de Oro\u201d en la Liga Mexicana del Pac\u00edfico (LMP), el camarero sonorense est\u00e1 por arrancar su und\u00e9cima temporada con el conjunto fronterizo en la Liga Mexicana de Beisbol (LMB). A pesar de haberse convertido en uno de los veteranos del club, el diestro de 34 a\u00f1os insiste en que lejos del rendimiento individual, lo m\u00e1s importante en un equipo de b\u00e9isbol son los resultados colectivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201cTodos somos grandes jugadores y con mucha experiencia, con mucha hambre y muchas ganas, pero lo m\u00e1s importante es que la personalidad en el clubhouse es la misma y eso es clave en un equipo\u201d, coment\u00f3 previo al duelo del mi\u00e9rcoles en el Estadio Francisco I. Madero de Saltillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Y lo de \u201cganadores\u201d lo fundamenta en algo tan sencillo como el \u00e9xito en los diamantes internacionales que han registrado sus compa\u00f1eros a lo largo de sus carreras. Jugadores como Emilio Bonifacio, Junior Lake, Danny Ortiz, Aneury Tav\u00e1rez, Al\u00ed Sol\u00eds, Hern\u00e1n P\u00e9rez son buenos ejemplos para hacer uso de la palabra \u201cganadores\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201c\u00bfCu\u00e1ntos jugadores de Toros de Tijuana han estado en la Serie del Caribe o en alguna final en cada uno de sus pa\u00edses como Puerto Rico, Venezuela, Rep\u00fablica Dominicana? Sin duda alguna somos puros ganadores y se ha demostrado aqu\u00ed desde el primer d\u00eda de pretemporada y cada quien seguir\u00e1 poniendo su granito de arena para empezar con todo desde el 18 de abril\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>De su Guante de Oro prefiere no hablar mucho. No le atraen los reconocimientos individuales, al menos as\u00ed lo ha expresado a lo largo de su carrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201cEs satisfactorio (ganar Guante de Oro), pero no hay nada como festejar en conjunto, es mucho mejor qu\u00e9 en lo individual\u201d, asegur\u00f3 mientras se alistaba para el cuarto juego de pretemporada contra Saraperos. \u201cSiempre agradecido con la organizaci\u00f3n de Ca\u00f1eros de Los Mochis por seguir d\u00e1ndome la oportunidad y seguir confiando en mi persona y en mi trabajo, sin embargo, lo que est\u00e1 en mi mente de la temporada pasada es que nos quedamos cortos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Fue su tercer reconocimiento defensivo en temporadas consecutivas. Su porcentaje de fildeo en 2024-25 fue de .994 al registrar s\u00f3lo dos errores en 329 oportunidades durante 66 juegos.<br>La pelota invernal ya es cosa del pasado y ahora se prepara para un intento m\u00e1s en busca de la \u00fanica cifra que le quita el sue\u00f1o: La de los campeonatos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201cAqu\u00ed en Toros de Tijuana siempre el objetivo es m\u00ednimo llegar a la final\u201d, subray\u00f3.<br>Aunque se resista, la numerolog\u00eda lo seguir\u00e1 en cada juego, sobre todo en la campa\u00f1a 2025 cuando estar\u00e1 muy cerca de varios hitos que no s\u00f3lo son de su carrera, sino de la historia misma de Toros de Tijuana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Isaac necesita veinte hits para convertirse en el primer jugador en la historia del club con 800 imparables. Requiere de 24 carreras empujadas m\u00e1s para ser el primero con trescientas en la organizaci\u00f3n y once robos para llegar a 150, otra cifra que tambi\u00e9n es la m\u00e1xima de la franquicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>A eso s\u00famele que con 34 carreras anotadas m\u00e1s ser\u00e1 el primero con quinientas en el equipo fronterizo. Adem\u00e1s, si logra aparecer en la alineaci\u00f3n del 18 de abril, se convertir\u00e1 en el \u00fanico jugador de Toros de Tijuana con participaci\u00f3n en diez juegos inaugurales y todos de forma concatenada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Pero el n\u00famero m\u00e1s importante que busca alcanzar es el tres, algo que podr\u00eda lograr en conjunto con un viejo compa\u00f1ero que acaba de reintegrarse a la \u201cembestida\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201cCon Lupe Ch\u00e1vez han sido ocho o nueve a\u00f1os, no tengo idea de cu\u00e1ntas dobles matanzas hemos hecho, pero muy contento y todav\u00eda aprendiendo de \u00e9l igual que cuando llegu\u00e9. La confianza que nos tenemos el uno al otro es algo muy especial\u201d, asegur\u00f3.<br>El primero de ese n\u00famero tres lo consigui\u00f3 en 2017 junto a \u00d3scar Robles, quien sigue siendo su mentor, s\u00f3lo que ahora lo hace de forma oficial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201cRecuerdo cuando entre a batear el 30 de julio del 2015, todav\u00eda guardo la alineaci\u00f3n en el cuarto y nunca se me va a olvidar ese momento y esa pr\u00e1ctica donde estaba tomando rolas con \u00e9l (\u00d3scar Robles), luego me iba para las paradas cortas y para segunda. Son momentos que no se olvidan\u201d, concluy\u00f3.<br>El segundo lo gan\u00f3 en 2021.<br>Y el tercero se asoma a la distancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con \u201cGuante de Oro\u201d en la mano, Isaac Rodr\u00edguez apunta su mira a la Serie del Rey del 2025 TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 4 de abril del 2025 Isaac Rodr\u00edguez no tiene ninguna duda, en Toros de Tijuana hay puros ganadores. El estelar segunda base acelera su puesta a punto y asegura que la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13783,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-13782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=13782"}],"version-history":[{"count":2,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13782\/revisions"}],"predecessor-version":[{"id":15366,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13782\/revisions\/15366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/13783"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=13782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=13782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=13782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}