{"id":13679,"date":"2025-03-18T08:57:29","date_gmt":"2025-03-18T15:57:29","guid":{"rendered":"https:\/\/torosdetijuana.com\/?p=13679"},"modified":"2025-08-29T15:08:55","modified_gmt":"2025-08-29T22:08:55","slug":"el-cambio-definitivo","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/el-cambio-definitivo\/2025\/03\/","title":{"rendered":"\u201cEL CAMBIO DEFINITIVO\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con su cambio y en un cambio definitivo, Luis M\u00e1rquez ya est\u00e1 de regreso para su segunda temporada con Toros de Tijuana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 17 de marzo del 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Un cambio de velocidad trajo a<a href=\"https:\/\/www.diablos.com.mx\/jugador\/luis-marquez-700587\" title=\"\"> Luis M\u00e1rquez<\/a> a Toros de Tijuana en 2023 y otro cambio lo regres\u00f3 para el 2025. El estelar relevista sonorense est\u00e1 de vuelta para fortalecer al mejor bullpen de la Liga Mexicana de Beisbol (LMB).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El zurdo de 27 a\u00f1os se ha convertido en uno de los mejores relevistas mexicanos y lo hace con un mortal cambio de velocidad que disfraza entre sus rectas que lucen m\u00e1s r\u00e1pidas cuando sorprenden a sus rivales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Cumpli\u00f3 con una temporada de lujo en su primera comparecencia con el uniforme de Toros de Tijuana en 2023. En 27 juegos registr\u00f3 marca de 5-0 en ganados y perdidos con efectividad de 1.90 y microsc\u00f3pico Whip de 0.887 en 23 entradas y un tercio en las que ponch\u00f3 a 21 a cambio de seis bases por bolas.<br>En 2025 viene por m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201cMuy contento por la oportunidad que me dan de volver a Tijuana me he sentido emocionado desde la primera pr\u00e1ctica y muy contento de volver\u201d, dijo al t\u00e9rmino de su primera pr\u00e1ctica con el conjunto tijuanense. \u201cEs una gran organizaci\u00f3n. Toros de Tijuana es uno de los mejores equipos de M\u00e9xico, me gusta la uni\u00f3n que hay aqu\u00ed y la competitividad de este equipo que siempre est\u00e1 peleando por ser los mejores y a entregarlo todo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Luego de un a\u00f1o con los Toros de Tijuana, el sonorense regres\u00f3 a El \u00c1guila de Veracruz al cumplirse el plazo de su pr\u00e9stamo. En 2024 jug\u00f3 muy poco debido a que pas\u00f3 por una operaci\u00f3n que lo mantuvo alejado de los diamantes.<br>Ahora ya est\u00e1 de regreso a la acci\u00f3n y a los bureles, al concretarse en octubre un cambio definitivo con el equipo veracruzano por el tambi\u00e9n lanzador Samuel Zazueta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201cMe siento al cien por ciento, pudimos salir gracias a Dios de esa operaci\u00f3n, hoy me siento muy bien y a seguir trabajando para poder darlo todo en la temporada. La entrega es al 100 por ciento, yo siempre vengo a dar todo de m\u00ed y eso es lo que vengo a hacer este a\u00f1o igual, sabemos que esto es b\u00e9isbol y todo puede pasar, pero hacemos lo mejor que podamos\u201d, agreg\u00f3.<br>Y si le dan a escoger, M\u00e1rquez prefiere estar del lado correcto de la historia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201cEs un equipo a vencer (Toros), cuando eres rival t\u00fa vienes a jugarles con todo, porque es uno de los mejores equipos de M\u00e9xico y siempre quieres ganarle porque es un gran reto, ahora gracias a Dios estamos de este lado\u201d, concluy\u00f3.<br>En 2022 Luis Ernesto M\u00e1rquez fue elegido como Novato del A\u00f1o en LMB.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LUIS M\u00c1RQUEZ<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Nombre: Luis Ernesto M\u00e1rquez<br>Lugar de nacimiento: Huatabampo, Sonora<br>Fecha de nacimiento: 29 de noviembre de 1997<br>Posici\u00f3n: Lanzador<br>Batea: Zurdo<br>Lanza: Zurdo<br>Equipos LMB: El \u00c1guila de Veracruz y Toros de Tijuana<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con su cambio y en un cambio definitivo, Luis M\u00e1rquez ya est\u00e1 de regreso para su segunda temporada con Toros de Tijuana.<\/p>\n","protected":false},"author":2,"featured_media":13678,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[],"class_list":["post-13679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=13679"}],"version-history":[{"count":2,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13679\/revisions"}],"predecessor-version":[{"id":15415,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13679\/revisions\/15415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/13678"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=13679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=13679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=13679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}