{"id":13614,"date":"2025-03-10T16:28:41","date_gmt":"2025-03-10T23:28:41","guid":{"rendered":"https:\/\/torosdetijuana.com\/?p=13614"},"modified":"2025-08-29T15:39:42","modified_gmt":"2025-08-29T22:39:42","slug":"el-papas-se-vistio-de-toro","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/el-papas-se-vistio-de-toro\/2025\/03\/","title":{"rendered":"\u201cEL PAPAS\u201d SE VISTI\u00d3 DE TORO"},"content":{"rendered":"\n<p class=\"MsoNormal wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\"><strong>Andr\u00e9s \u00c1lvarez report\u00f3 con anticipaci\u00f3n a la pretemporada de Toros de Tijuana con la mira puesta en la campa\u00f1a 2025 de Liga Mexicana de Beisbol&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\"><strong>TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 10 de marzo del 2025<\/strong><\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Le dicen \u201cEl Papas\u201d, creci\u00f3 en Tijuana\u00a0y el lunes\u00a0report\u00f3 a pretemporada. <a href=\"https:\/\/www.mlb.com\/es\/player\/andres-alvarez-687019?stats=career-r-hitting-minors&amp;year=2025\" title=\"\">Andr\u00e9s \u00c1lvarez<\/a>, una de las m\u00e1s recientes adiciones a Toros de Tijuana, respondi\u00f3 con anticipaci\u00f3n a la convocatoria para los trabajos de preparaci\u00f3n, al presentarse a la puesta a punto del conjunto fronterizo en el estadio de la Colonia Capistrano.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">El jugador de cuadro de 27 a\u00f1os fue confirmado en febrero como refuerzo de la embestida y ahora se prepara para cumplir con uno de sus sue\u00f1os m\u00e1s grandes como jugador profesional.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Naci\u00f3 en Chula Vista, California, pero, desde peque\u00f1o, su residencia ha sido Tijuana, donde dio sus primeros pasos en el b\u00e9isbol.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">\u201cYa me tocaba estar aqu\u00ed de este lado\u201d, dijo al finalizar su primera pr\u00e1ctica con el equipo. \u201cEstuve en muchos juegos como aficionado en la grada y ahora estoy ansioso y quiero que ya inicie la temporada\u201d<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">El sue\u00f1o de jugar en casa no es s\u00f3lo personal, sino que se extiende a toda su familia y amigos que ahora podr\u00e1n apoyarlo y alentarlo en cada juego que Toros de Tijuana dispute en el coloso del Cerro Colorado.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">\u201cYo creo que mi familia est\u00e1 m\u00e1s emocionada que yo porque nunca me hab\u00edan tenido tan cerca y ahora me imagino que por lo menos unos diez familiares y amigos estar\u00e1n a diario por aqu\u00ed en el estadio\u201d, agreg\u00f3 el bateador derecho.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Su arribo al trabajo no fue a terreno desconocido, ya que adem\u00e1s de conocer el estadio, tambi\u00e9n ha tenido contacto con la mayor\u00eda de quienes ser\u00e1n sus compa\u00f1eros, incluyendo el cuerpo t\u00e9cnico. \u00d3scar Robles, manejador de Toros de Tijuana, tambi\u00e9n lo dirigi\u00f3 hace unos meses con Tomateros de Culiac\u00e1n en la Liga Mexicana del Pac\u00edfico (LMP).<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">\u201cCon \u00d3scar me sent\u00ed muy c\u00f3modo como manejador, desde que llegu\u00e9 en Culiac\u00e1n me hizo sentir como en casa y ahora que yo ven\u00eda para Tijuana habl\u00e9 con \u00e9l antes de reportarme, me abri\u00f3 las puertas desde ese d\u00eda y me dijo que quer\u00eda que fuera parte del equipo\u201d, mencion\u00f3.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Para \u00c1lvarez la del 2025 ser\u00e1 su primera incursi\u00f3n en la Liga Mexicana de Beisbol (LMB), sin embargo, conoce muy bien el circuito, sobre todo a Toros de Tijuana que ha sido el equipo al que m\u00e1s ha seguido a la distancia.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">\u201cToros es un equipo que siempre va por el campeonato, es de los equipos protagonistas, de los fuertes. En el equipo siempre hay alguien detr\u00e1s de ti que puede hacer el trabajo y la meta siempre es quedar campe\u00f3n y vamos por eso\u201d, coment\u00f3.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Los jugadores de posici\u00f3n de Toros de Tijuana tienen el llamado a entrenamiento para&nbsp;el martes 18 de marzo, sin embargo, poco a poco empiezan a llegar algunos de los peloteros contemplados en el equipo \u201cgrande\u201d.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">\u201cYo quiero llegar listo, ten\u00eda ya rato que no estaba jugando as\u00ed que quiero prepararme para competir y estar listo para la temporada, adem\u00e1s estaba ansioso de llegar al estadio\u201d, concluy\u00f3.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">El lunes, \u00c1lvarez trabaj\u00f3 por primera ocasi\u00f3n con el equipo de su ciudad. Ahora viene lo m\u00e1s fuerte en busca de completar el anhelo de jugar en casa.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">\u201cEste a\u00f1o viene algo muy bueno para la ciudad porque vamos a darlo todo para tratar de quedar campeones y que se siga haciendo sentir el estadio. Aqu\u00ed los esperamos\u201d, concluy\u00f3.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">&nbsp;<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\"><strong>\u201cEL PAPAS\u201d<\/strong><\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Algo que ha acompa\u00f1ado a Andr\u00e9s \u00c1lvarez desde ni\u00f1o ha sido su pasi\u00f3n por el b\u00e9isbol y el apodo de \u201cEl Papas\u201d.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Lejos de molestarle, el sobrenombre ya est\u00e1 muy ligado a \u00e9l y lo toma con cari\u00f1o porque es de todos conocido, no s\u00f3lo en el b\u00e9isbol, sino en su familia y c\u00edrculo de amistades cercanas.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">\u201cNadie me dice Andr\u00e9s, yo creo que en mi familia uno o dos me dicen Andr\u00e9s, pero \u201cEl Papas\u201d es desde peque\u00f1o, desde que tengo memoria ha sido mi apodo porque com\u00eda muchas papitas de chiquito\u201d, explic\u00f3 con una sonrisa grande.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Las bolsas de papitas eran su vicio y as\u00ed se le ve\u00eda muy seguido, sobre todo cuando participaba en ligas infantiles de Tijuana.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">\u201cDonde me mirabas yo tra\u00eda mi bolsita de papitas y en los campos de Otay se me qued\u00f3 el apodo y hasta la fecha as\u00ed me conoce la gente\u201d, asegur\u00f3.<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">&nbsp;<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\"><strong>ANDR\u00c9S \u00c1LVAREZ<\/strong><\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Lugar de nacimiento:&nbsp;&nbsp;&nbsp; Chula Vista, California<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Fecha de nacimiento:&nbsp;&nbsp;&nbsp; 29 de marzo de 1997<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Posici\u00f3n:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Jugador de cuadro<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Lanza:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Derecho<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Batea:&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Derecho<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Organizaci\u00f3n MLB:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Piratas de Pittsburgh<\/p>\n\n\n\n<p class=\"MsoNormal wp-block-paragraph\">Equipos LMB:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Toros de Tijuana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andr\u00e9s \u00c1lvarez report\u00f3 con anticipaci\u00f3n a la pretemporada de Toros de Tijuana con la mira puesta en la campa\u00f1a 2025 de Liga Mexicana de Beisbol\u00a0<\/p>\n","protected":false},"author":2,"featured_media":13613,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[506,182,188,267],"class_list":["post-13614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-andres-alvarez","tag-lmb","tag-tijuana","tag-toros"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=13614"}],"version-history":[{"count":2,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13614\/revisions"}],"predecessor-version":[{"id":15428,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/13614\/revisions\/15428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/13613"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=13614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=13614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=13614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}