{"id":12327,"date":"2024-07-29T21:30:17","date_gmt":"2024-07-30T04:30:17","guid":{"rendered":"https:\/\/torosdetijuana.com\/?p=12327"},"modified":"2024-07-29T21:30:18","modified_gmt":"2024-07-30T04:30:18","slug":"ultima-serie-en-casa","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/ultima-serie-en-casa\/2024\/07\/","title":{"rendered":"\u00daLTIMA SERIE EN CASA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Toros de Tijuana cerrar\u00e1 la temporada regular cuando reciba a Dorados de Chihuahua en el Estadio Chevron.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TIJUANA, Baja California (TorosDeTijuana.com-Armando Esquivel) 29 de julio del 2024.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"1066\" src=\"https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59.jpeg\" alt=\"\" class=\"wp-image-12328\" srcset=\"https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59.jpeg 1600w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59-600x400.jpeg 600w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59-300x200.jpeg 300w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59-1024x682.jpeg 1024w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59-768x512.jpeg 768w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59-1536x1023.jpeg 1536w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59-128x85.jpeg 128w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59-32x21.jpeg 32w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59-1200x800.jpeg 1200w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59-90x60.jpeg 90w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59-330x220.jpeg 330w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59-680x453.jpeg 680w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-29-at-21.13.59-920x613.jpeg 920w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Toros de Tijuana buscar\u00e1 ascender en la tabla de posiciones<\/strong> cuando reciba\u00a0a Dorados de Chihuahua en la \u00faltima serie de la temporada regular 2024 de Liga Mexicana de Beisbol (LMB).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los encuentros de martes a jueves <strong>iniciar\u00e1n a las 19:35 horas<\/strong> en los amigables confines del <strong>Estadio Chevron<\/strong> y con esos duelos caer\u00e1 el tel\u00f3n del calendario regular y se definir\u00e1 la tabla general de la Zona Norte de cara a los <strong><a href=\"https:\/\/torosdetijuana.com\/index.php\/2024\/07\/26\/una-decada-en-playoffs\/\" title=\"\">playoffs.<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El conjunto fronterizo enviar\u00e1 al mont\u00edculo a dos de sus cartas fuertes <\/strong>para despedir la campa\u00f1a regular, ya que el martes abrir\u00e1 <strong><a href=\"https:\/\/www.milb.com\/es\/player\/juan-perez-607372\" title=\"\">Juan P\u00e9rez<\/a><\/strong> (8-1; 2.82) y el mi\u00e9rcoles trabajar\u00e1 <a href=\"https:\/\/www.mlb.com\/es\/player\/zac-lowther-675912\" title=\"\">Zac Lowther<\/a> (2-1; 2.18), mientras que el jueves a\u00fan no est\u00e1 definido al serpentinero que pasar\u00e1 la bola para el cierre de temporada regular, pero los candidatos son Wendolyn Bautista (4-6; 5.11) y Nick Wells (1-1; 2.93).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cuerpo t\u00e9cnico de Dorados de Chihuahua anunci\u00f3 que sus lanzadores abridores para la serie en Tijuana ser\u00e1n Christian Torres (3-0; 3.00), <strong>Fernando Olguin<\/strong> (1-1; 5.76) y Pablo Garabitos (0-2; 14.25).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ser\u00e1 la primera ocasi\u00f3n que Toros de Tijuana enfrente a Dorados de Chihuahua en el Estadio Chevron, <\/strong>sin embargo, ya se midieron en dos series que tuvieron como escenario el Estadio Monumental y los astados ganaron ambas con balance general de cuatro victorias y dos derrotas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los bureles llegar\u00e1n a esta serie luego de barrer a Caliente de Durango el fin de semana y tienen r\u00e9cord de <strong>49-40<\/strong> en la quinta posici\u00f3n de la Zona Norte, a cuatro juegos del l\u00edder Sultanes de Monterrey.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Dorados de Chihuahua tiene 33-57 en el fondo del pelot\u00f3n norte\u00f1o y ya sin aspiraciones de postemporada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toros de Tijuana cerrar\u00e1 la temporada regular, con serie en casa, cuando reciba a Dorados de Chihuahua en el Estadio Chevron.<\/p>\n","protected":false},"author":2,"featured_media":12329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[312,313,188,267],"class_list":["post-12327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-chihuahua","tag-dorados","tag-tijuana","tag-toros"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/12327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=12327"}],"version-history":[{"count":2,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/12327\/revisions"}],"predecessor-version":[{"id":12331,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/12327\/revisions\/12331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/12329"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=12327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=12327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=12327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}