{"id":12098,"date":"2024-06-29T00:53:04","date_gmt":"2024-06-29T07:53:04","guid":{"rendered":"https:\/\/torosdetijuana.com\/?p=12098"},"modified":"2024-06-29T00:53:05","modified_gmt":"2024-06-29T07:53:05","slug":"liga-toros-su-cuarta-victoria-en-gira","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/liga-toros-su-cuarta-victoria-en-gira\/2024\/06\/","title":{"rendered":"LIGA TOROS SU CUARTA VICTORIA EN GIRA\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><strong>La escuadra fronteriza volvi\u00f3 a marcar doble d\u00edgito de imparables y se llev\u00f3 el primero de la serie en Chihuahua.<\/strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CHIHUAHUA, Chihuahua(TorosDeTijuana-Sebasti\u00e1n Acosta) 28 de junio del 2024.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-1024x683.jpg\" alt=\"\" class=\"wp-image-12099\" srcset=\"https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-1024x683.jpg 1024w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-600x400.jpg 600w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-300x200.jpg 300w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-768x512.jpg 768w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-1536x1024.jpg 1536w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-128x85.jpg 128w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-32x21.jpg 32w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-1200x800.jpg 1200w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-90x60.jpg 90w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-330x220.jpg 330w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-680x453.jpg 680w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2-920x613.jpg 920w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/IB3A0490-2.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Blake Rutherford, Bobby Bradley y Matt Adams <strong>se destaparon con sendos cuadrangulares<\/strong>, en apoyo a una gran labor de Teddy Stankiewicz sobre la loma, que le permiti\u00f3 a Toros de Tijuana pegar primero ante Dorados de Chihuahua, tras vencerlos por pizarra de<strong> 5-3 <\/strong>la noche de este viernes en el Estadio Monumental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el resultado, los fronterizos sumaron su cuarto triunfo de manera consecutiva, todos en carretera, y movieron su foja de temporada a <strong>34 victorias por 29 derrotas<\/strong>, para mantenerse en el quinto puesto de la Zona Norte, a seis juegos y medio del l\u00edder Sultanes de Monterrey.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pizarra <strong>se abri\u00f3 en la segunda entrada<\/strong> y fueron los locales quienes pegaron primero, cuando un triple hacia el jard\u00edn central derecho, de Manny Garc\u00eda, se combin\u00f3 con un sencillo de Sergio Burruel que le dio a Dorados la ventaja por la m\u00ednima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Toros empat\u00f3 las acciones en el cuarto cap\u00edtulo<\/strong> con el madero de Blake Rutherford como protagonista, quien mand\u00f3 a volar la bola por todo el jard\u00edn derecho para poner el 1-1 en el marcador. Ese fue su cuarto cuadrangular en doce encuentros disputados con el equipo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La respuesta Dorada fue inmediata<\/strong> y apenas media entrada despu\u00e9s, retomaron la ventaja, luego de que H\u00e9ctor Mora abri\u00f3 la tanda con doblete, avanz\u00f3 a la antesala con toque de sacrificio de Jes\u00fas Mart\u00ednez y lleg\u00f3 a la registradora con rodado al cuadro de Carlos Herrera, retomando la ventaja con el <strong>2-1.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rally grande del compromiso, que le dio rumbo definitivo, <strong>lleg\u00f3 en la s\u00e9ptima \u201cde la suerte\u201d<\/strong>, fue de la visita y con dos outs en la pizarra. Lo comenz\u00f3 Donny Sands, al recibir al relevista Heitor Tokar con imparable de una base.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par de turnos despu\u00e9s, Aneury Tav\u00e1rez <strong>le hizo segunda para tener hombres en las esquinas<\/strong>, mientras que Bobby Bradley se encarg\u00f3 de remolcar a todos, con un potente tablazo por el jard\u00edn derecho central que le dio la vuelta al marcador con el<strong> 4 por 2.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sergio Burruel volvi\u00f3 a hacer el juego peque\u00f1o, cuando <strong>abri\u00f3 la parte baja del s\u00e9ptimo rollo<\/strong> con tabla solitaria, sin embargo, <a href=\"https:\/\/torosdetijuana.com\/index.php\/2024\/01\/29\/toros-sembrara-el-terror-en-2024-firma-matt-adams\/\" title=\"\">Matt Adams<\/a> pag\u00f3 con la misma moneda para descontar la anotaci\u00f3n rival, conectando un potente tablazo hacia la pradera derecha que termin\u00f3 cincelando el <strong>5 por 3 definitivo <\/strong>en los cartones.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u00a1MATT ADAMS! HOME RUN solitario, su n\u00famero 10 de la temporada y su carrera producida 40\ud83d\udd25 <a href=\"https:\/\/t.co\/YIW93ronN5\">pic.twitter.com\/YIW93ronN5<\/a><\/p>&mdash; Toros De Tijuana \ud83d\udc03 (@TorosDeTijuana) <a href=\"https:\/\/twitter.com\/TorosDeTijuana\/status\/1806892612370268163?ref_src=twsrc%5Etfw\">June 29, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SOBRE EL MONT\u00cdCULO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Teddy Stankiewicz se subi\u00f3 al mont\u00edculo<\/strong> y consigui\u00f3 su segundo triunfo de la temporada, cumpliendo con otra buena labor en la que lanz\u00f3 seis episodios de seis hits, dos carreras, una base por bolas y recet\u00f3 tres chocolates.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el bullpen, lo apoyaron Jared Wilson con dos outs en la s\u00e9ptima y Jos\u00e9 \u00c1lvarez complet\u00f3 el asalto. En la octava trabaj\u00f3 Silvino Bracho y colg\u00f3 el cero en cuatro bateadores, mientras que Roel Ram\u00edrez sali\u00f3 por tres outs en la novena tanda, para conseguir su onceavo rescate del a\u00f1o..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del lado chihuahuense, fue el venezolano <strong>Henry Centeno el abridor y sali\u00f3 sin decisi\u00f3n<\/strong>, luego de seis entradas en los que permiti\u00f3 seis hits, una carrera, dio dos dos pasaportes y ponch\u00f3 a cuatro. A su relevo salieron el perdedor Heitor Tokar, Carlos Navas, Liarvis Breto y Sasagi S\u00e1nchez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CONTIN\u00daAN LA SERIE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toros y Dorados <a href=\"https:\/\/www.milb.com\/mexican\/news\/lmb-calendario-oficial-de-la-temporada-2024-de-la-liga-mexicana-de-beisbol\" title=\"\">contin\u00faan con su \u00faltima estancia de la temporada en Chihuahua este s\u00e1bado<\/a>, cuando disputen el segundo encuentro de la serie desde el Estadio Monumental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para subirse a la lomita est\u00e1n programados el derecho Jorge P\u00e9rez (5-1, 3.19), por el bando astado, y el zurdo australiano, Lewis Thorpe (0-5, 4.44) por los del &#8220;estado grande&#8221;, en punto de las 17:00 horas (horario de Tijuana).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PIZARRA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EQUIPO \u00a0 \u00a0 \u00a0 123 \u00a0 456 \u00a0 789\u00a0 \u00a0C \u00a0 H\u00a0 E<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tijuana:&nbsp; &nbsp; &nbsp; &nbsp; 000 &nbsp; 100 &nbsp; 310&nbsp; &nbsp; 5&nbsp; 11&nbsp; 1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chihuahua: &nbsp; 010 &nbsp; 010 &nbsp; 100&nbsp; &nbsp;3 &nbsp; 9 &nbsp; 0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pitcher ganador:&nbsp; &nbsp; &nbsp; Teddy Stankiewicz (2-1, 2.84)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pitcher derrotado: Heitor Tokar (0-1, 13.50)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuadrangulares: Blake Rutherford, Bobby Bradley, Matt Adams (TIJ) | Sergio Burruel (CHI) &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estadio: Estadio Monumental<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asistencia: &nbsp; &nbsp; &nbsp; Mil 303 aficionados&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Duraci\u00f3n: 3 hora con 16 minutos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La escuadra fronteriza volvi\u00f3 a marcar doble d\u00edgito de imparables y se llev\u00f3 el primero de la serie en Chihuahua.<\/p>\n","protected":false},"author":2,"featured_media":12100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[312,313,188,267],"class_list":["post-12098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-chihuahua","tag-dorados","tag-tijuana","tag-toros"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/12098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=12098"}],"version-history":[{"count":1,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/12098\/revisions"}],"predecessor-version":[{"id":12101,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/12098\/revisions\/12101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/12100"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=12098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=12098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=12098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}