{"id":12078,"date":"2024-06-26T00:30:24","date_gmt":"2024-06-26T07:30:24","guid":{"rendered":"https:\/\/torosdetijuana.com\/?p=12078"},"modified":"2024-06-26T00:30:55","modified_gmt":"2024-06-26T07:30:55","slug":"se-encienden-maderos-y-pegan-en-durango","status":"publish","type":"post","link":"https:\/\/torosdetijuana.com\/index.php\/se-encienden-maderos-y-pegan-en-durango\/2024\/06\/","title":{"rendered":"SE ENCIENDEN MADEROS Y PEGAN EN DURANGO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><strong>La escuadra fronteriza abri\u00f3 la gira con victoria al vencer por 22-8 a Caliente de Durango.<\/strong>\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DURANGO, Durango (TorosDeTijuana-Sebasti\u00e1n Acosta) 25 de junio del 2024.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-1024x682.jpg\" alt=\"\" class=\"wp-image-12079\" srcset=\"https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-1024x682.jpg 1024w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-600x400.jpg 600w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-300x200.jpg 300w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-768x512.jpg 768w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-1536x1023.jpg 1536w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-128x85.jpg 128w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-32x21.jpg 32w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-1200x800.jpg 1200w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-90x60.jpg 90w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-330x220.jpg 330w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-680x453.jpg 680w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2-920x613.jpg 920w, https:\/\/torosdetijuana.com\/wp-content\/uploads\/2024\/06\/photo1719369029-2.jpg 1921w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Toros de Tijuana <strong>se destap\u00f3 con 22 imparables<\/strong> e iniciaron con <a href=\"https:\/\/torosdetijuana.com\/index.php\/2024\/06\/24\/buscara-toros-enracharse-en-durango\/\" title=\"\">el pie derecho la estancia en carretera<\/a>, luego de apalear a Caliente de Durango por pizarra de<strong> 22-8 <\/strong>para pegar primero en la serie desde el Estadio Francisco Villa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aneury Tavarez <strong>se estren\u00f3 en grande como ca\u00f1onero<\/strong> del equipo, conectando el <strong>segundo grand slam de la temporada<\/strong>, mientras que Junior Lake se meti\u00f3 a los r\u00e9cords con un cuadrangular de campo dentro de la enorme jornada ofensiva burel.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u00a1Aneury Tav\u00e1rez vuelve a hacer da\u00f1o, esta vez con sencillo que parte el diamante en dos! Anota Sands y anota Castro.<a href=\"https:\/\/twitter.com\/hashtag\/M%C3%A1sAcci%C3%B3nM%C3%A1sDiversi%C3%B3n?src=hash&amp;ref_src=twsrc%5Etfw\">#M\u00e1sAcci\u00f3nM\u00e1sDiversi\u00f3n<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/TorosAqu%C3%AD?src=hash&amp;ref_src=twsrc%5Etfw\">#TorosAqu\u00ed<\/a>\ud83d\udc03\ud83d\udccd<br>Presentado por <a href=\"https:\/\/twitter.com\/calientesports?ref_src=twsrc%5Etfw\">@CalienteSports<\/a><br>\u27a1\ufe0f <a href=\"https:\/\/t.co\/gFvJsKCoY1\">https:\/\/t.co\/gFvJsKCoY1<\/a> <a href=\"https:\/\/t.co\/koZeyvW88j\">pic.twitter.com\/koZeyvW88j<\/a><\/p>&mdash; Toros De Tijuana \ud83d\udc03 (@TorosDeTijuana) <a href=\"https:\/\/twitter.com\/TorosDeTijuana\/status\/1805786001362895197?ref_src=twsrc%5Etfw\">June 26, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Los pupilos de Dan Firova no esperaron nada y en el primer cap\u00edtulo <strong>tomaron ventaja<\/strong>, luego de que Harold Castro <strong>abri\u00f3 el juego con doblete<\/strong>, avanz\u00f3 con hit de Jack Mayfield y timbr\u00f3 gracias a un rodado al cuadro de Aneury Tavarez para <strong>la primera rayita del juego.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rally grande del juego cay\u00f3 desde la segunda tanda de los astados y comenz\u00f3 con un pasaporte a Niko V\u00e1squez. Le siguieron un doble de Blake Rutherford y sencillo de Donny Sands para el <strong>2-0<\/strong>, mientras que con casa llena, Aneury Tavarez respondi\u00f3 y <strong>trajo dos m\u00e1s al plato.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Philli Evans, Matt Adams y Niko V\u00e1squez <strong>se unieron a la fiesta con sencillo, doble y base por bolas, <\/strong>respectivamente, que a\u00f1adieron tres m\u00e1s, pero fue el madero de Blake Rutherford el que sell\u00f3 el ataque <strong>con cuadrangular<\/strong> por todo el centro que movi\u00f3 la pizarra al <strong>10 por 0<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La cosa no par\u00f3 y por tercer episodio consecutivo Toros lleg\u00f3 al plato, <\/strong>ahora en tres ocasiones, cuando un roletazo de Tavarez mand\u00f3 al plato a Harold Castro y Matt Adams hizo lo propio con Jack Mayfield y Phillip Evans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los locales se quitaron el cerro en la tercera por la v\u00eda del \u201ccaballito\u201d para que <strong>Carlos Garz\u00f3n <\/strong>llegara al plato; Manuel Bosc\u00e1n, Luis Avil\u00e9s y L\u00e1zaro Alonso siguieron con sencillos de Ariel Sandoval y Jos\u00e9 Manuel Orozco que completaron el rally de cuatro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, <strong>un solo swing fue suficiente para contrarrestar dichas anotaciones<\/strong>, pues Aneury Tavarez se sirvi\u00f3 \u201ccon la cuchara grande\u201d y mand\u00f3 a volar la pelota hacia el jard\u00edn derecho, aprovechando a sus tres compa\u00f1eros en circulaci\u00f3n para el grand slam que protagoniz\u00f3 el racimo de la cuarta entrada, poniendo las cosas <strong>17-4.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Doblete de Sam Travis y sencillo de Manuel Bosc\u00e1n <strong>aumentaron a seis las carreras de Caliente<\/strong>, pero nuevamente <strong>la ofensiva tijuanense descont\u00f3 con par de rayitas<\/strong>. Una en la sexta tanda con hit de Matt Adams, y la otra en la s\u00e9ptima, cuando Junior Lake aprovech\u00f3 un batazo contra el muro del central que se le complic\u00f3 a los jardineros, permiti\u00e9ndole completar la vuelta a las bases con un cuadrangular de campo para el <strong>19-6.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00faltimo cap\u00edtulo no se salv\u00f3 de ver carreras y <strong>tres fueron de los Toros<\/strong>, con el primer vuelacercas de Donny Sands en su regreso que se llev\u00f3 por delante a Jairus Richards y Junior Lake.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cifras definitivas las pusieron los propios duranguenses en el cierre de ese asalto, y por la misma v\u00eda, pues Ariel Sandoval dio sencillo y Jos\u00e9 Manuel Orozco lo mand\u00f3 al pent\u00e1gono con tablazo por el central que cincel\u00f3 el <strong>22 por 8 final.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SOBRE EL MONT\u00cdCULO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El joven ensenadense<strong> Fernando Lozano abri\u00f3 por los astados<\/strong> y sali\u00f3 sin decisi\u00f3n, con pelota de tres episodios en los que le hicieron ocho carreras, regal\u00f3 un pasaporte y recet\u00f3 un chocolate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su relevo salieron el boricua y ganador, Christian Torres, que colg\u00f3 argolla en la cuarta, Jes\u00fas Pirela trabaj\u00f3 en blanco con dos ponches en el quinto rollo y Ricardo Rodr\u00edguez camin\u00f3 tranquilo en la sexta. Many Barreda lanz\u00f3 las siguientes dos sin novedades y Fernando Olgu\u00edn lanz\u00f3 en la novena, permitiendo dos carreras que solo adornaron el marcador en el trounfo tijuanense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por los locales, el brasile\u00f1o <strong>Tiago Da Silva sali\u00f3 a su octava apertura del a\u00f1o<\/strong> y carg\u00f3 con el descalabro, luego de una corta labor en la que lanz\u00f3 una entrada y out de seis imparables, siete carreras, regal\u00f3 dos bases por bolas y ponch\u00f3 a un rival. Luis Ram\u00edrez, Juan Robles, Ozzie M\u00e9ndez, Gunnar Kines, Baltazar Arredondo y Wendell Floranus salieron a su apoyo desde el bullpen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CONTIN\u00daA LA SERIE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toros y Caliente se vuelven a ver las caras este mi\u00e9rcoles por la noche, para un segundo duelo en el que est\u00e1n programados para subirse a la loma el derecho Jake Thompson, por la escuadra de Dan Firova, y Frank Duncan por los duranguenses, en punto de las 18:35 horas (horario de Tijuana) desde el Estadio Francisco Villa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PIZARRA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EQUIPO\u00a0 \u00a0 \u00a0 \u00a0 123 \u00a0 \u00a0 456 \u00a0 \u00a0 789 \u00a0 \u00a0C \u00a0 H \u00a0 E<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tijuana:&nbsp; &nbsp; &nbsp; &nbsp; 193 &nbsp; &nbsp; 401 &nbsp; &nbsp; 103&nbsp; &nbsp; 22&nbsp; 22 0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durango: &nbsp; &nbsp; &nbsp; 004 &nbsp; &nbsp; 200 &nbsp; &nbsp; 002 &nbsp; 8 &nbsp; 15&nbsp; 0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pitcher ganador: &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Christian Torres (1-0, 4.50)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pitcher derrotado:&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Tiago Da Silva (2-4, 8.50)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuadrangulares:&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Blake Rutherford, Aneury Tavarez, Junior Lake, Donny Sands (TIJ) | Jos\u00e9 Manuel Orozco (DUR)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estadio:&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Estadio Francisco Villa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asistencia:&nbsp; &nbsp; &nbsp; 970 aficionados&nbsp;&nbsp;&nbsp;Duraci\u00f3n: 4 horas con 1 minuto<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La escuadra fronteriza abri\u00f3 la gira con victoria al vencer por 22-8 a Caliente de Durango.<\/p>\n","protected":false},"author":2,"featured_media":12080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[375,201,188,267],"class_list":["post-12078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-caliente-de-durango","tag-durango","tag-tijuana","tag-toros"],"_links":{"self":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/12078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/comments?post=12078"}],"version-history":[{"count":2,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/12078\/revisions"}],"predecessor-version":[{"id":12082,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/posts\/12078\/revisions\/12082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media\/12080"}],"wp:attachment":[{"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/media?parent=12078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/categories?post=12078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/torosdetijuana.com\/index.php\/wp-json\/wp\/v2\/tags?post=12078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}